{"id":12164,"date":"2015-02-05T11:01:25","date_gmt":"2015-02-05T15:01:25","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=12164"},"modified":"2015-02-05T11:01:25","modified_gmt":"2015-02-05T15:01:25","slug":"cidade-pernambucana-registra-dois-tremores-de-terra","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2015\/02\/05\/cidade-pernambucana-registra-dois-tremores-de-terra\/","title":{"rendered":"Cidade Pernambucana registra dois tremores de terra"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-12165\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/02\/brasil-terremoto-pernambuco.jpg\" alt=\"_brasil terremoto pernambuco\" width=\"500\" height=\"325\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/02\/brasil-terremoto-pernambuco.jpg 500w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/02\/brasil-terremoto-pernambuco-300x195.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Dois tremores de terra foram registrados em Caruaru, no Agreste de Pernambuco, nesta ter\u00e7a-feira (3). De acordo com uma an\u00e1lise do Laborat\u00f3rio Sismol\u00f3gico da Universidade Federal do Rio Grande do Norte (LabSis\/UFRN), respons\u00e1vel por monitorar abalos s\u00edsmicos no Nordeste, o maior dos tremores marcou 2.0 graus na chamada Escala Richter, que vai de 0 a 10.\u00a0<!--more--><\/p>\n<p>\u201cFizemos um c\u00e1lculo de dois eventos que aconteceram nesta ter\u00e7a. Um foi \u00e0s 11h58, e outro maior que ocorreu logo em seguida. Este chegou a 2.0 graus. Outros eventos costumam ocorrer em Caruaru, mas s\u00e3o de pequena intensidade e n\u00e3o devem causar temores \u00e0 popula\u00e7\u00e3o\u201d, explicou o f\u00edsico da UFRN, Neimar Pereira. Ainda segundo o t\u00e9cnico, uma an\u00e1lise mais detalhada dos abalos est\u00e1 sendo realizada. A Defesa Civil do munic\u00edpio n\u00e3o registrou nenhuma v\u00edtima ou danos materiais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois tremores de terra foram registrados em Caruaru, no Agreste de Pernambuco, nesta ter\u00e7a-feira (3). De acordo com uma an\u00e1lise do Laborat\u00f3rio Sismol\u00f3gico da Universidade Federal do Rio Grande do Norte (LabSis\/UFRN), respons\u00e1vel por monitorar abalos s\u00edsmicos no Nordeste, o maior dos tremores marcou 2.0 graus na chamada Escala Richter, que vai de 0 a 10.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":12165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[7,1],"tags":[],"views":2389,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/12164"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=12164"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/12164\/revisions"}],"predecessor-version":[{"id":12166,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/12164\/revisions\/12166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/12165"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=12164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=12164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=12164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}