{"id":13084,"date":"2015-03-26T13:35:10","date_gmt":"2015-03-26T17:35:10","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=13084"},"modified":"2015-04-02T03:05:00","modified_gmt":"2015-04-02T07:05:00","slug":"84-dos-brasileiros-acreditam-que-dilma-sabia-de-corrupcao-na-petrobras-aponta-pesquisa","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2015\/03\/26\/84-dos-brasileiros-acreditam-que-dilma-sabia-de-corrupcao-na-petrobras-aponta-pesquisa\/","title":{"rendered":"84% dos brasileiros acreditam que Dilma sabia de corrup\u00e7\u00e3o na Petrobras, aponta pesquisa"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-13085\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/03\/dilma1.jpg\" alt=\"dilma\" width=\"500\" height=\"309\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/03\/dilma1.jpg 500w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/03\/dilma1-300x185.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Pesquisa Datafolha divulgada no domingo (22), pelo jornal Folha de S\u00e3o Paulo, mostra que para 84% dos entrevistados, a presidente Dilma Rousseff sabia da corrup\u00e7\u00e3o na Petrobras, tema da investiga\u00e7\u00e3o da Opera\u00e7\u00e3o Lava Jato. O levantamento nacional, realizado nos dias 16 e 17 deste m\u00eas, portanto logo ap\u00f3s as manifesta\u00e7\u00f5es populares contra o governo, diz que desse total, 61% consideram que a presidente sabia da corrup\u00e7\u00e3o e \u201cdeixou que acontecesse\u201d, enquanto 23% acreditam que \u201cela n\u00e3o poderia fazer nada para evit\u00e1-la\u201d. <!--more--><\/p>\n<p>A outra pergunta feita sobre se a descoberta de corrup\u00e7\u00e3o na Petrobras prejudica a empresa, 88% dos entrevistados responderam que sim, dos quais 51% julgam que ser\u00e1 por muito tempo e que coloca o futuro da empresa em risco. Outros 23% consideram que ser\u00e1 por pouco tempo, sem riscos futuros. $Privatiza\u00e7\u00e3o$ Para 61% dos brasileiros, a Petrobras deve continuar sob controle estatal, conforme pesquisa do Datafolha. Outros 24% s\u00e3o a favor da privatiza\u00e7\u00e3o, de acordo com o levantamento. A rejei\u00e7\u00e3o \u00e0 venda da petroleira, envolvida em esc\u00e2ndalos de corrup\u00e7\u00e3o, \u00e9 maior entre os entrevistados que declaram apoio ao PT, de 67%. Entre os simpatizantes do PSDB, 56% s\u00e3o contra e 35% a favor. A pesquisa foi realizada com 2842 pessoas em 172 munic\u00edpios brasileiros, e a margem de erro \u00e9 de dois pontos porcentuais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa Datafolha divulgada no domingo (22), pelo jornal Folha de S\u00e3o Paulo, mostra que para 84% dos entrevistados, a presidente Dilma Rousseff sabia da corrup\u00e7\u00e3o na Petrobras, tema da investiga\u00e7\u00e3o da Opera\u00e7\u00e3o Lava Jato. O levantamento nacional, realizado nos dias 16 e 17 deste m\u00eas, portanto logo ap\u00f3s as manifesta\u00e7\u00f5es populares contra o governo, diz que desse total, 61% consideram que a presidente sabia da corrup\u00e7\u00e3o e \u201cdeixou que acontecesse\u201d, enquanto 23% acreditam que \u201cela n\u00e3o poderia fazer nada para evit\u00e1-la\u201d.<\/p>\n","protected":false},"author":1,"featured_media":13085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[7,1],"tags":[],"views":1930,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/13084"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=13084"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/13084\/revisions"}],"predecessor-version":[{"id":13086,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/13084\/revisions\/13086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/13085"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=13084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=13084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=13084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}