{"id":13099,"date":"2015-03-26T14:57:59","date_gmt":"2015-03-26T18:57:59","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=13099"},"modified":"2015-03-26T14:57:59","modified_gmt":"2015-03-26T18:57:59","slug":"forma-potente-de-maconha-triplica-risco-de-psicose-diz-estudo","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2015\/03\/26\/forma-potente-de-maconha-triplica-risco-de-psicose-diz-estudo\/","title":{"rendered":"Forma potente de maconha triplica risco de psicose, diz estudo"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-13100\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/03\/maconha.jpg\" alt=\"maconha\" width=\"499\" height=\"300\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/03\/maconha.jpg 499w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/03\/maconha-300x180.jpg 300w\" sizes=\"(max-width: 499px) 100vw, 499px\" \/><\/p>\n<p>Vers\u00e3o potente da maconha, o skunk, pode triplicar o risco de psicose, diz um estudo da universidade brit\u00e2nica King&#8217;s College London. Realizada com 780 pessoas, a pesquisa mostrou que usu\u00e1rios da droga t\u00eam tr\u00eas vezes mais chances de desenvolver o quadro do que os n\u00e3o usu\u00e1rios.<\/p>\n<p>Os cientistas do Instituto de Psiquiatria, Psicologia e Neuroci\u00eancia da universidade conclu\u00edram tamb\u00e9m que o uso de haxixe, outro tipo da cannabis, n\u00e3o est\u00e1 associado ao risco de psicose.<!--more--><\/p>\n<p>Em compara\u00e7\u00e3o com aqueles que nunca tinham experimentado cannabis, usu\u00e1rios de cannabis de alta pot\u00eancia do tipo skunk tiveram um aumento de tr\u00eas vezes no risco de psicose, afirmou \u00e0 BBC Marta Di Forti, principal autora da pesquisa. Os resultados mostram que o risco de psicose em usu\u00e1rios de maconha depende da frequ\u00eancia de uso e pot\u00eancia da cannabis. A pesquisadora afirmou ainda que o uso do skunk est\u00e1 cada vez mais generalizado em Londres, embora a droga seja proibida na Inglaterra. O skunk cont\u00e9m mais THC &#8211; princ\u00edpio psicoativo da cannabis &#8211; que outros tipos de maconha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vers\u00e3o potente da maconha, o skunk, pode triplicar o risco de psicose, diz um estudo da universidade brit\u00e2nica King&#8217;s College London. Realizada com 780 pessoas, a pesquisa mostrou que usu\u00e1rios da droga t\u00eam tr\u00eas vezes mais chances de desenvolver o quadro do que os n\u00e3o usu\u00e1rios. Os cientistas do Instituto de Psiquiatria, Psicologia e Neuroci\u00eancia da universidade conclu\u00edram tamb\u00e9m que o uso de haxixe, outro tipo da cannabis, n\u00e3o est\u00e1 associado ao risco de psicose.<\/p>\n","protected":false},"author":1,"featured_media":13100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[4,1],"tags":[],"views":2081,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/13099"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=13099"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/13099\/revisions"}],"predecessor-version":[{"id":13101,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/13099\/revisions\/13101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/13100"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=13099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=13099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=13099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}