{"id":14754,"date":"2015-06-11T14:44:58","date_gmt":"2015-06-11T18:44:58","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=14754"},"modified":"2015-06-11T14:44:58","modified_gmt":"2015-06-11T18:44:58","slug":"do-lixo-ao-luxo-brasileiro-faz-arte-com-objetos-descartados-em-new-york","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2015\/06\/11\/do-lixo-ao-luxo-brasileiro-faz-arte-com-objetos-descartados-em-new-york\/","title":{"rendered":"&#8220;Do lixo ao luxo&#8221;, brasileiro faz arte com objetos descartados em New York"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-14755\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/06\/lixo.jpg\" alt=\"lixo\" width=\"500\" height=\"409\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/06\/lixo.jpg 500w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/06\/lixo-300x245.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>As lixeiras dos americanos s\u00e3o conhecidas por terem m\u00f3veis, eletr\u00f4nicos e diversos objetos de valor que s\u00e3o descartados ainda novos. Enquanto uns desperdi\u00e7am, outros usam a criatividade para ganhar a vida com o que os outros jogam no lixo.<!--more--><\/p>\n<p>Esse \u00e9 o caso do carioca Vinicius Ribeiro, de 38 anos, que encontrou nesses dumpsters (ca\u00e7ambas de lixo) o ouro que precisava para sua arte. &#8220;Eu acho muita coisa nova no lixo. O que n\u00e3o serve para mim hoje vai servir para algu\u00e9m amanh\u00e3. E a minha casa \u00e9 toda assim. Meu trabalho \u00e9 esse, transformar o lixo em luxo, em lixo chique. Infelizmente na nossa cultura s\u00f3 damos valor \u00e0s coisas novas que s\u00e3o sa\u00eddas das lojas. N\u00e3o temos o h\u00e1bito de reciclar e transformar. E isso \u00e9 maravilhoso&#8221;, diz Vinicius. Objetos como cadeiras, mesas, esculturas, pufes, espelhos, mesas, sapatos, vestidos, quadros, sof\u00e1s e cadeiras que, a primeira vista, s\u00e3o simples e sem vida, se tornam pe\u00e7as de decora\u00e7\u00e3o que viram a tiete de qualquer sala, quarto ou cen\u00e1rios para fotos e eventos.<\/p>\n<p>Ele saiu do Rio de Janeiro em 2001 e veio para os Estados Unidos estudar. Ribeiro conta que saiu do Brasil por n\u00e3o ter liberdade para viver sua vida, muito menos sua arte. &#8220;Venho de uma fam\u00edlia com valores tradicionais e eu precisava ser livre. Encontrei essa liberdade na Am\u00e9rica. Por aqui empregados e empregadores est\u00e3o no mesmo patamar. Hoje somos servidos, amanh\u00e3 poderemos servir. Vi que as pessoas aqui s\u00e3o respeitadas pelo que elas s\u00e3o e vi que era isso que eu queria&#8221;, disse.<\/p>\n<p>Vinicius conta que sempre conviveu com as artes desde pequeno. J\u00e1 trabalhou como ator e, em New York, estudou pintura. Sua inspira\u00e7\u00e3o \u00e9 o artista pl\u00e1stico Vik Muniz, radicado em NY e famoso por criar pe\u00e7as com objetos retirados do lixo, restos de demoli\u00e7\u00e3o e at\u00e9 alimentos. &#8220;Tive a oportunidade de conhecer Vik Muniz numa festa e fiquei impressionado com sua simpatia e humildade. \u00c9 um grande artista e minha inspira\u00e7\u00e3o&#8221;, completa.<\/p>\n<p>Hoje Ribeiro trabalha em parceria com o fot\u00f3grafo brasileiro Clecio Lira na produ\u00e7\u00e3o de cen\u00e1rios para fotos. Ele tamb\u00e9m \u00e9 produtor de eventos. &#8220;Os amigos tamb\u00e9m me pedem que eu transforme o lixo em objetos de decora\u00e7\u00e3o&#8221;, acrescenta. O objetivo do artista \u00e9 que seu trabalho chegue a uma galeria de arte em New York. Quem estiver interessado em conhecer um pouco mais sobre o trabalho de Vinicius Ribeiro vinnienyc212@gmail.com ou no Facebook Dumpster Chick.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As lixeiras dos americanos s\u00e3o conhecidas por terem m\u00f3veis, eletr\u00f4nicos e diversos objetos de valor que s\u00e3o descartados ainda novos. Enquanto uns desperdi\u00e7am, outros usam a criatividade para ganhar a vida com o que os outros jogam no lixo.<\/p>\n","protected":false},"author":1,"featured_media":14755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[4,1],"tags":[],"views":2965,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/14754"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=14754"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/14754\/revisions"}],"predecessor-version":[{"id":14756,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/14754\/revisions\/14756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/14755"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=14754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=14754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=14754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}