{"id":14764,"date":"2015-06-11T14:50:12","date_gmt":"2015-06-11T18:50:12","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=14764"},"modified":"2015-06-11T14:50:12","modified_gmt":"2015-06-11T18:50:12","slug":"professora-brasileira-de-universidade-de-new-jersey-faz-programa-de-radio-para-americanos-praticarem-o-portugues","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2015\/06\/11\/professora-brasileira-de-universidade-de-new-jersey-faz-programa-de-radio-para-americanos-praticarem-o-portugues\/","title":{"rendered":"Professora brasileira de universidade de New Jersey faz programa de r\u00e1dio para americanos praticarem o portugu\u00eas"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-14765\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/06\/americanos.jpg\" alt=\"americanos\" width=\"500\" height=\"287\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/06\/americanos.jpg 500w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/06\/americanos-300x172.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Por semestre, cerca de 160 alunos da Rutgers University, a universidade p\u00fablica de New Jersey, escolhem o portugu\u00eas para estudar como idioma estrangeiro, como parte da grade curricular, entre quase dez outros cursos de l\u00ednguas dispon\u00edveis.<!--more--><\/p>\n<p>A jornalista brasileira Daiane Tamanaha \u00e9 professora de um dos cursos oferecidos\u00a0 na universidade e, este semestre, resolveu finalizar o curso criando um programa de r\u00e1dio em portugu\u00eas para &#8220;tirar o medo dos alunos&#8221; de se comunicar na l\u00edngua estrangeira. &#8220;Pensei no programa de r\u00e1dio como projeto final do curso que leciono porque, como jornalista, sei que o r\u00e1dio \u00e9 um instrumento que ajuda a desinibir porque voc\u00ea fala com muitas pessoas, usando apenas o microfone&#8221;, explica.<\/p>\n<p>Os alunos aprovaram a ideia. &#8220;Eu achei muito legal e muito divertido!\u2019\u2019, disse (em portugu\u00eas) o americano de fam\u00edlia porto-riquenha, Erio David Perales, de 18 anos. Ele conta que mora pr\u00f3ximo ao Ironbound, uma regi\u00e3o conhecida por ter a maior comunidade brasileira em New Jersey. A proximidade tamb\u00e9m o tem ajudado a praticar o que aprendeu nas aulas na universidade.<\/p>\n<p>O programa de r\u00e1dio, chamado Hot Portuguese 102, ter\u00e1 tr\u00eas edi\u00e7\u00f5es, cada uma com 30 minutos, que ser\u00e3o transmitidas, ainda sem data definida, pela r\u00e1dio da universidade, a Rutgers Radio Station. Ser\u00e1 a primeira vez que a r\u00e1dio transmitir\u00e1 um programa em portugu\u00eas. Cada programa tem nove m\u00fasicas dos mais variados ritmos, desde rock, sertanejo, funk e MPB. &#8220;O programa ter\u00e1 ainda informa\u00e7\u00f5es sobre a l\u00edngua portuguesa no mundo e sobre os cursos de portugu\u00eas da universidade, al\u00e9m de not\u00edcias sobre o Brasil\u2019\u2019, diz.<\/p>\n<p>Daiane Tamanaha, chegou aos Estados Unidos em 2010, acompanhando o marido, \u00a0pesquisador em neuroci\u00eancia na Princeton University. Com o Brasil &#8220;na moda&#8221;, \u00a0devido a campanha exaustiva na m\u00eddia, primeiro sobre a Copa do Mundo, e agora por causa das Olimp\u00edadas de 2016 no Rio de Janeiro,\u00a0Daiane tem encontrado v\u00e1rias oportunidades para divulgar a l\u00edngua portuguesa. \u2018\u2019J\u00e1 dei aulas na Princeton University, na University of Delaware e agora na Rutgers\u2019\u2019, comemora.<\/p>\n<p>Enquanto para alguns o portugu\u00eas parece interessante por estar &#8220;na moda&#8221;, para outros aprender o idioma significa manter e estreitar as ra\u00edzes familiares.\u00a0 Matthew Bielasiak, de 19 anos, cuja m\u00e3e \u00e9 brasileira, entende quando as pessoas falam em portugu\u00eas, mas admite que ainda n\u00e3o tem confian\u00e7a para se comunicar usando a l\u00edngua portuguesa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por semestre, cerca de 160 alunos da Rutgers University, a universidade p\u00fablica de New Jersey, escolhem o portugu\u00eas para estudar como idioma estrangeiro, como parte da grade curricular, entre quase dez outros cursos de l\u00ednguas dispon\u00edveis.<\/p>\n","protected":false},"author":1,"featured_media":14765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[4,1],"tags":[],"views":2105,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/14764"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=14764"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/14764\/revisions"}],"predecessor-version":[{"id":14766,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/14764\/revisions\/14766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/14765"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=14764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=14764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=14764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}