{"id":18127,"date":"2015-10-29T17:16:48","date_gmt":"2015-10-29T21:16:48","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=18127"},"modified":"2015-10-29T17:16:48","modified_gmt":"2015-10-29T21:16:48","slug":"apos-abate-de-quase-300-ursos-em-dois-dias-florida-encerra-temporada-de-caca","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2015\/10\/29\/apos-abate-de-quase-300-ursos-em-dois-dias-florida-encerra-temporada-de-caca\/","title":{"rendered":"Ap\u00f3s abate de quase 300 ursos em dois dias, Fl\u00f3rida encerra temporada de ca\u00e7a"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-18128\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/10\/bear-urso.jpg\" alt=\"OLYMPUS DIGITAL CAMERA\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/10\/bear-urso.jpg 500w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2015\/10\/bear-urso-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Bastaram dois dias para um total de 295 ursos negros serem abatidos na Fl\u00f3rida, quando o estado reabriu a temporada de ca\u00e7a depois de 21 anos.<\/p>\n<p>O n\u00famero de animais mortos foi confirmado pelo Florida Fish and Wildlife Conservation Commission (FWC), que suspendeu a temporada ainda no domigo, dia 25, devido ao alto n\u00famero de abate no fim de semana.<!--more--><\/p>\n<p>O limite estipulado pela comiss\u00e3o era de 320 ursos, mas em duas das quatro regi\u00f5es autorizadas para ca\u00e7ada, o limite de ursos mortos foi atingido logo no primeiro dia.<\/p>\n<p>Em todo o estado, cerca de 3,7 mil ca\u00e7adores haviam comprado licen\u00e7as de ca\u00e7a de urso \u2013 aproximadamente 335 deles no sul da Fl\u00f3rida.<\/p>\n<p>Segundo o FWC, a decis\u00e3o de reabrir a temporada de ca\u00e7a se deu pelo fato da popula\u00e7\u00e3o de ursos no estado estar em aproximadamente em 3,5 mil animais, enquanto na d\u00e9cada de 70 era estimada em apenas 300. A comiss\u00e3o alega que o alto n\u00famero de ursos apresenta perigo aos humanos.<\/p>\n<p>De acordo com autoridades da Fl\u00f3rida, mais de 200 ursos s\u00e3o mortos por carros nas estradas estaduais a cada ano.<\/p>\n<p>Com informa\u00e7\u00f5es do \u201cSun Sentinel\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bastaram dois dias para um total de 295 ursos negros serem abatidos na Fl\u00f3rida, quando o estado reabriu a temporada de ca\u00e7a depois de 21 anos. O n\u00famero de animais mortos foi confirmado pelo Florida Fish and Wildlife Conservation Commission (FWC), que suspendeu a temporada ainda no domigo, dia 25, devido ao alto n\u00famero de abate no fim de semana.<\/p>\n","protected":false},"author":1,"featured_media":18128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[4,1],"tags":[],"views":2726,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/18127"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=18127"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/18127\/revisions"}],"predecessor-version":[{"id":18129,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/18127\/revisions\/18129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/18128"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=18127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=18127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=18127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}