{"id":20285,"date":"2016-01-28T13:24:46","date_gmt":"2016-01-28T17:24:46","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=20285"},"modified":"2016-01-28T13:24:46","modified_gmt":"2016-01-28T17:24:46","slug":"fla-mira-zagueiro-de-ponta-na-america-do-sul-para-acalmar-torcida-e-muricy","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2016\/01\/28\/fla-mira-zagueiro-de-ponta-na-america-do-sul-para-acalmar-torcida-e-muricy\/","title":{"rendered":"Fla mira zagueiro de ponta na Am\u00e9rica do Sul para acalmar torcida e Muricy"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-20286\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2016\/01\/flamengo1.jpg\" alt=\"flamengo\" width=\"500\" height=\"300\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2016\/01\/flamengo1.jpg 500w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2016\/01\/flamengo1-300x180.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Dois jogos amistosos e seis gols sofridos foram suficientes para manter o alerta ligado no Flamengo. A necessidade de refor\u00e7ar o sistema defensivo com um zagueiro de ponta j\u00e1 era admitida internamente e ganhou for\u00e7a depois que o t\u00e9cnico Muricy Ramalho cobrou.<\/p>\n<p>&#8220;Para compor o elenco temos v\u00e1rios zagueiros. Mas sentimos que precisamos de um jogador ali. N\u00e3o podemos errar. N\u00e3o d\u00e1 para trazer qualquer um. Tem que ser jogador de ponta no mercado, o que \u00e9 dif\u00edcil encontrar. Estamos atr\u00e1s disso&#8221;, afirmou o comandante ap\u00f3s a derrota por 3 a 1 para o Santa Cruz.<!--more--><\/p>\n<p>O discurso de Muricy encontra eco na torcida. A cobran\u00e7a por um nome de relev\u00e2ncia para a posi\u00e7\u00e3o \u00e9 crescente a cada apresenta\u00e7\u00e3o. Resta apenas o zagueiro para fechar o elenco da primeira parte da temporada. Se nenhuma oportunidade inesperada de mercado surgir, o nome vir\u00e1 da Am\u00e9rica do Sul.<\/p>\n<p>Alejandro Donatti, do Rosario Central, j\u00e1 esteve perto de acertar contrato. Os argentinos pedem em torno de R$ 8 milh\u00f5es para liber\u00e1-lo. A negocia\u00e7\u00e3o est\u00e1 em curso, mas ainda n\u00e3o evoluiu como esperado. Victor Cuesta, do Independiente-ARG, \u00e9 outro nome trabalhado na G\u00e1vea.<\/p>\n<p>O modelo de zagueiro est\u00e1 definido. A diretoria quer um defensor alto e r\u00e1pido para substituir Wallace. A tend\u00eancia \u00e9 a de que o refor\u00e7o entre diretamente no time titular para formar dupla com o veterano Juan. Os cartolas tentam resolver o problema com rapidez, mas tamb\u00e9m esbarram no or\u00e7amento.<\/p>\n<p>A ideia inicial era a de parcelar o pagamento ao clube do zagueiro escolhido. A partir de agora, por\u00e9m, outras formas de fechar o neg\u00f3cio s\u00e3o consideradas. O Rubro-negro corre contra o tempo para entregar o melhor ao t\u00e9cnico Muricy Ramalho e tem no discurso do &#8220;erro zero&#8221; a base fundamentada.<\/p>\n<p>&#8220;Como ele [Muricy Ramalho] disse, n\u00e3o podemos errar. Por isso leva tempo, j\u00e1 que tudo \u00e9 feito em comum acordo com a comiss\u00e3o t\u00e9cnica&#8221;, encerrou o vice-presidente de futebol, Fl\u00e1vio Godinho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois jogos amistosos e seis gols sofridos foram suficientes para manter o alerta ligado no Flamengo. A necessidade de refor\u00e7ar o sistema defensivo com um zagueiro de ponta j\u00e1 era admitida internamente e ganhou for\u00e7a depois que o t\u00e9cnico Muricy Ramalho cobrou. &#8220;Para compor o elenco temos v\u00e1rios zagueiros. Mas sentimos que precisamos de um jogador ali. N\u00e3o podemos errar. N\u00e3o d\u00e1 para trazer qualquer um. Tem que ser jogador de ponta no mercado, o que \u00e9 dif\u00edcil encontrar. Estamos atr\u00e1s disso&#8221;, afirmou o comandante ap\u00f3s a derrota por 3 a 1 para o Santa Cruz.<\/p>\n","protected":false},"author":1,"featured_media":20286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[9,1],"tags":[],"views":2071,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/20285"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=20285"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/20285\/revisions"}],"predecessor-version":[{"id":20287,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/20285\/revisions\/20287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/20286"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=20285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=20285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=20285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}