{"id":23925,"date":"2016-08-04T14:34:51","date_gmt":"2016-08-04T18:34:51","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=23925"},"modified":"2016-08-11T14:29:39","modified_gmt":"2016-08-11T18:29:39","slug":"novas-regras-de-imigracao-a-partir-de-29-de-agosto","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2016\/08\/04\/novas-regras-de-imigracao-a-partir-de-29-de-agosto\/","title":{"rendered":"Novas regras de imigra\u00e7\u00e3o a partir de 29 de agosto"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-23926\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2016\/08\/imigracao.jpg\" alt=\"imigracao\" width=\"500\" height=\"281\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2016\/08\/imigracao.jpg 500w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2016\/08\/imigracao-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>A partir de 29 de agosto governo edita novas regras para o perd\u00e3o migrat\u00f3rio para unificar fam\u00edlias.<\/strong><\/p>\n<p>A partir do pr\u00f3ximo dia 29 de agosto, residentes legais dos EUA que est\u00e3o no pa\u00eds e que tenham c\u00f4njuges, pais ou filhos indocumentados poder\u00e3o aplicar para o USCIS e pedir a concess\u00e3o de uma isen\u00e7\u00e3o que lhes permitir\u00e1 ajustar seu status de imigra\u00e7\u00e3o.<!--more--><\/p>\n<p>A regra final anunciada pela USCIS estende o processo de isen\u00e7\u00e3o tempor\u00e1ria existente para permitir que pessoas que s\u00e3o parentes de cidad\u00e3os americanos e residentes permanentes legais, e que s\u00e3o legalmente eleg\u00edveis para vistos de imigrantes, possam obter mais facilmente o processo de imigra\u00e7\u00e3o, de acordo com o comunicado de imprensa emitido sexta-feira.<\/p>\n<p>O processo de isen\u00e7\u00e3o provis\u00f3ria promove a unidade da fam\u00edlia, reduzindo o tempo que as pessoas eleg\u00edveis permanecem separadas de suas fam\u00edlias ao completar o processo de imigra\u00e7\u00e3o no exterior, ao mesmo tempo melhora a efici\u00eancia administrativa, disse o comunicado.<\/p>\n<p>Esta extens\u00e3o do perd\u00e3o existia apenas para os c\u00f4njuges e filhos de cidad\u00e3os norte-americanos.<\/p>\n<p>Esse perd\u00e3o exonerar as pessoas do castigo de tr\u00eas a 10 anos que foram impostas por viverem ilegalmente nos EUA.<\/p>\n<p>As leis de imigra\u00e7\u00e3o afirmam que uma pessoa que tenha vivido ilegalmente no pa\u00eds entre seis meses e um ano, recebeu uma pena de tr\u00eas anos e, no caso de uma pessoa que ficou por mais de um ano, imediatamente a penalidade sobe a 10 anos.<\/p>\n<p>Atualmente, os parentes pr\u00f3ximos dos residentes legais, para se candidatar a esse perd\u00e3o, ter\u00e3o de regressar aos seus pa\u00edses de origem e, a partir da\u00ed, ingressar o processo de ajuste de status no respectivo consulado dos EUA. Agora n\u00e3o estar\u00e3o mais sujeitos a qualquer forma de puni\u00e7\u00e3o.<\/p>\n<p>De acordo com as autoridades de imigra\u00e7\u00e3o o processo de ajuste de imigra\u00e7\u00e3o ser\u00e1 acelerado.<\/p>\n<p>Esta norma aplica-se a pessoas que entram no pa\u00eds atrav\u00e9s da passagem ilegal de fronteira e quem permaneceu no pa\u00eds al\u00e9m do tempo permitido por seus vistos.<\/p>\n<p>Para se qualificar para a isen\u00e7\u00e3o tempor\u00e1ria, os candidatos devem demonstrar que os seus c\u00f4njuges ou pais cidad\u00e3os americanos ou residentes permanentes legais est\u00e3o em &#8220;extrema dificuldade&#8221; se os requerentes n\u00e3o forem autorizados a voltar para os EUA.<\/p>\n<p>O comunicado sublinha que os candidatos n\u00e3o devem apresentar o Formul\u00e1rio I-601A, pedido de ren\u00fancia de presen\u00e7a ilegal antes de 29 de agosto de 2016, pois o USCIS pode negar o pedido.<\/p>\n<p>A norma foi publicada sexta-feira no Federal Register, o jornal onde todas as regras devem ser publicadas antes de entrar em vigor.<\/p>\n<p>Os interessados \u200b\u200bdevem utilizar o formul\u00e1rio I-601A ap\u00f3s essa data.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de 29 de agosto governo edita novas regras para o perd\u00e3o migrat\u00f3rio para unificar fam\u00edlias. A partir do pr\u00f3ximo dia 29 de agosto, residentes legais dos EUA que est\u00e3o no pa\u00eds e que tenham c\u00f4njuges, pais ou filhos indocumentados poder\u00e3o aplicar para o USCIS e pedir a concess\u00e3o de uma isen\u00e7\u00e3o que lhes permitir\u00e1 ajustar seu status de imigra\u00e7\u00e3o.<\/p>\n","protected":false},"author":1,"featured_media":23926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1,10],"tags":[],"views":7353,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/23925"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=23925"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/23925\/revisions"}],"predecessor-version":[{"id":23927,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/23925\/revisions\/23927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/23926"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=23925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=23925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=23925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}