{"id":30605,"date":"2017-09-21T12:09:34","date_gmt":"2017-09-21T16:09:34","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=30605"},"modified":"2017-09-21T12:09:34","modified_gmt":"2017-09-21T16:09:34","slug":"diogo-barbosa-quer-a-taca-para-ser-visto-com-outros-olhos-no-futebol-brasileiro","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2017\/09\/21\/diogo-barbosa-quer-a-taca-para-ser-visto-com-outros-olhos-no-futebol-brasileiro\/","title":{"rendered":"Diogo Barbosa quer a ta\u00e7a para ser visto com &#8220;outros olhos&#8221; no futebol brasileiro"},"content":{"rendered":"<p>Outubro de 2010. PC Gusm\u00e3o, ent\u00e3o t\u00e9cnico do Vasco,\u00a0confirma o jovem Diogo\u00a0na lateral esquerda do time para um cl\u00e1ssico contra o Flamengo. &#8220;Se tiver brilho no olho, vai ter oportunidade&#8221;, disse o treinador na ocasi\u00e3o. Diogo &#8220;virou&#8221; Diogo Barbosa, passou por Sport, Guarani, Coritiba, Atl\u00e9tico-GO, Goi\u00e1s e Botafogo, chegou ao Cruzeiro em 2017 e est\u00e1 a poucos dias de enfrentar novamente o Flamengo, agora em circunst\u00e2ncias totalmente diferentes e no jogo mais importante da carreira. Diogo seguiu a dica do antigo treinador, mostrou brilho no olho, mostrou futebol e, hoje, \u00e9 titular absoluto do time de Mano Menezes. Se naquele jogo ele &#8220;s\u00f3&#8221; queria fazer uma boa estreia e come\u00e7ar bem a carreira de profissional, hoje quer muito mais: a ta\u00e7a da Copa do Brasil.<\/p>\n<p>&#8211; Eu tinha 18 anos, era moleque ainda. Tive uma oportunidade com o PC, treinador que me deu oportunidade de subir. Eu era muito verde ainda, por isso n\u00e3o tive uma sequ\u00eancia t\u00e3o boa. Mas faz parte, tive uma rodagem, estou vindo de tr\u00eas anos bem. Quero usufruir de tudo o que o Cruzeiro me proporciona e crescer ainda mais. Quero ser um \u00eddolo aqui, porque criei uma identifica\u00e7\u00e3o muito r\u00e1pida no Cruzeiro. A torcida me abra\u00e7ou muito, isso ajuda muito. Torcida, diretoria, todos. Isso tem sido importante para o meu crescimento. Tenho muito a crescer ainda, tentar ajudar cada vez mais o Cruzeiro a conquistar t\u00edtulos, que \u00e9 o que importa para o clube.<\/p>\n<p>A trajet\u00f3ria de Diogo Barbosa est\u00e1 demonstrando uma evolu\u00e7\u00e3o grande. Aos poucos, vai mostrando regularidade e aparecendo para o futebol brasileiro com um destaque maior. E \u00e9 exatamente isso que ele quer: conquistar a Copa do Brasil para ser visto com &#8220;outros olhos&#8221; Brasil afora.<\/p>\n<p>&#8211; Quando fui contratado, vi que tinha muita desconfian\u00e7a. Estava vindo do Botafogo, n\u00e3o tinha muito nome. Futebol n\u00e3o \u00e9 nome, futebol \u00e9 qualidade. Voc\u00ea tem que mostrar sua qualidade o tempo todo. Tive minha oportunidade, tentei abra\u00e7ar da melhor forma poss\u00edvel. Quero crescer ainda mais no Cruzeiro. Quero conquistar o t\u00edtulo, vai ser de muita import\u00e2ncia para o meu crescimento, para come\u00e7ar a ser visto com outros olhos no pa\u00eds. Cruzeiro me proporciona tudo que eu preciso para crescer como jogador.<\/p>\n<p><strong>&#8220;Muito inteligente&#8221;<\/strong><\/p>\n<p>Para que os resultados apare\u00e7am em campo, decis\u00f5es fora dele precisam ser tomadas com precis\u00e3o. Quando Diogo resolveu aceitar a proposta do Cruzeiro, colocou algo &#8211; ou algu\u00e9m, para ser mais exato &#8211; na balan\u00e7a da decis\u00e3o: Mano Menezes.<\/p>\n<p>&#8211; Tive outras propostas, mas queria um grande clube e um grande treinador. Na minha cabe\u00e7a, o Mano est\u00e1 entre os melhores. \u00c9 um cara muito inteligente. Pensamento foi esse. Quando tive a proposta do Cruzeiro, j\u00e1 falei para o meu empres\u00e1rio que queria o Cruzeiro. Me oferecia isso, toda a estrutura para trabalhar e um grande treinador, um treinador que eu tinha certeza que me faria crescer. Ele me ajuda muito, vai me ajudar ainda mais. Tenho certeza que tenho crescido muito em coisas que posso melhorar. Ele tem tirado isso de mim, tentado melhorar coisas que n\u00e3o s\u00e3o perfeitas. Quero aprender sempre. Conquistando esse t\u00edtulo, acho que eu ganho uma dimens\u00e3o maior, acho que as pessoas v\u00e3o come\u00e7ar a me olhar com outros olhos.<\/p>\n<p>\u00c9 v\u00e1lido lembrar que Diogo Barbosa foi, recentemente, mencionado duas vezes por Tite, t\u00e9cnico da Sele\u00e7\u00e3o, que garantiu que est\u00e1 de olho no atleta. A regularidade joga a seu favor. O t\u00edtulo da Copa do Brasil, caso venha, certamente vai ajud\u00e1-lo a ficar ainda mais perto de vestir a amarelinha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Outubro de 2010. PC Gusm\u00e3o, ent\u00e3o t\u00e9cnico do Vasco,\u00a0confirma o jovem Diogo\u00a0na lateral esquerda do time para um cl\u00e1ssico contra o Flamengo. &#8220;Se tiver brilho no olho, vai ter oportunidade&#8221;, disse o treinador na ocasi\u00e3o. Diogo &#8220;virou&#8221; Diogo Barbosa, passou por Sport, Guarani, Coritiba, Atl\u00e9tico-GO, Goi\u00e1s e Botafogo, chegou ao Cruzeiro em 2017 e est\u00e1 a poucos dias de enfrentar novamente o Flamengo, agora em circunst\u00e2ncias totalmente diferentes e no jogo mais importante da carreira. Diogo seguiu a dica do antigo treinador, mostrou brilho no olho, mostrou futebol e, hoje, \u00e9 titular absoluto do time de Mano Menezes. Se naquele [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[9,1],"tags":[],"views":1572,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/30605"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=30605"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/30605\/revisions"}],"predecessor-version":[{"id":30608,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/30605\/revisions\/30608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/30606"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=30605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=30605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=30605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}