{"id":31787,"date":"2017-11-30T16:14:36","date_gmt":"2017-11-30T20:14:36","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=31787"},"modified":"2017-11-30T16:14:36","modified_gmt":"2017-11-30T20:14:36","slug":"murilo-ou-arthur-cabral-volta-e-o-ataque-as-duvidas-de-mano-para-o-adeus-de-2017","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2017\/11\/30\/murilo-ou-arthur-cabral-volta-e-o-ataque-as-duvidas-de-mano-para-o-adeus-de-2017\/","title":{"rendered":"Murilo ou Arthur? Cabral volta? E o ataque? As d\u00favidas de Mano para o adeus de 2017"},"content":{"rendered":"<p>Para o 74\u00ba e \u00faltimo jogo na temporada, o t\u00e9cnico Mano Menezes tem d\u00favidas para montar o Cruzeiro para enfrentar o Botafogo, no Rio de Janeiro, no pr\u00f3ximo domingo, no est\u00e1dio Nilton Santos, \u00e0s 17h (de Bras\u00edlia). H\u00e1 incertezas da escala\u00e7\u00e3o na zaga, na dupla de volantes e tamb\u00e9m no ataque cruzeirense.<\/p>\n<p>Com o zagueiro L\u00e9o suspenso, o treinador cruzeirense s\u00f3 tem \u00e0 disposi\u00e7\u00e3o Dig\u00e3o, Murilo e Arthur. O primeiro dever\u00e1 ser mantido como titular. O segundo est\u00e1 com dores musculares na coxa direita e ser\u00e1 novamente avaliado pelo departamento m\u00e9dico. O terceiro subiu com 17 anos nesta temporada e est\u00e1 \u00e0 disposi\u00e7\u00e3o de voltar a atuar com Mano.<\/p>\n<p>&#8211; Expectativa muito grande, mas tamb\u00e9m tem o Murilo que est\u00e1 com um pouco de dor. Mas se o Mano optar por mim, estou preparado. Temos um jogo importante, o campeonato ainda n\u00e3o acabou e vamos tentar buscar esta vit\u00f3ria no \u00faltimo jogo &#8211; avaliou Arthur.<\/p>\n<p>No meio de campo, conforme Mano Menezes havia dito na v\u00e9spera do jogo contra o Vasco, Ariel Cabral, recuperado de uma cirurgia no tornozelo esquerdo, est\u00e1 nos planos para a partida e pode at\u00e9 ser titular. Para a posi\u00e7\u00e3o, Mano Menezes ainda tem Henrique, Lucas Silva, Nonoca e Lucas Romero.<\/p>\n<p>Entretanto, o argentino poder\u00e1, novamente, ser utilizado na lateral direita, j\u00e1 que Ezequiel passou por cirurgia e Rafael Galhardo sofreu uma les\u00e3o no reto femoral da coxa esquerda. Na esquerda, Bryan dever\u00e1 ganhar uma nova chance.<\/p>\n<p>No ataque, a d\u00favida \u00e9 se Jonata voltar\u00e1 a atuar. O atacante, utilizado como titular diante de Ava\u00ed e Vit\u00f3ria, teve um corte no superc\u00edlio contra o time baiano e ficou fora do \u00faltimo jogo. Outro que tem a expectativa de volta \u00e9 Rafael Sobis. No jogo contra o Fluminense, h\u00e1 duas semanas, ele levou uma pancada na coxa esquerda e, desde ent\u00e3o, n\u00e3o se recuperou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para o 74\u00ba e \u00faltimo jogo na temporada, o t\u00e9cnico Mano Menezes tem d\u00favidas para montar o Cruzeiro para enfrentar o Botafogo, no Rio de Janeiro, no pr\u00f3ximo domingo, no est\u00e1dio Nilton Santos, \u00e0s 17h (de Bras\u00edlia). H\u00e1 incertezas da escala\u00e7\u00e3o na zaga, na dupla de volantes e tamb\u00e9m no ataque cruzeirense. Com o zagueiro L\u00e9o suspenso, o treinador cruzeirense s\u00f3 tem \u00e0 disposi\u00e7\u00e3o Dig\u00e3o, Murilo e Arthur. O primeiro dever\u00e1 ser mantido como titular. O segundo est\u00e1 com dores musculares na coxa direita e ser\u00e1 novamente avaliado pelo departamento m\u00e9dico. O terceiro subiu com 17 anos nesta temporada e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[9,1],"tags":[],"views":1841,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31787"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=31787"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31787\/revisions"}],"predecessor-version":[{"id":31789,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31787\/revisions\/31789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/31788"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=31787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=31787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=31787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}