{"id":31799,"date":"2017-11-30T16:19:39","date_gmt":"2017-11-30T20:19:39","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=31799"},"modified":"2017-11-30T16:19:39","modified_gmt":"2017-11-30T20:19:39","slug":"coreia-do-norte-lanca-missil-trump-cobra-verbas-para-a-seguranca","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2017\/11\/30\/coreia-do-norte-lanca-missil-trump-cobra-verbas-para-a-seguranca\/","title":{"rendered":"Coreia do Norte lan\u00e7a m\u00edssil; Trump cobra verbas para a seguran\u00e7a"},"content":{"rendered":"<p>Pelo\u00a0Twitter, o presidente dos Estados Unidos, Donald Trump, defendeu ontem (28) a libera\u00e7\u00e3o de financiamento para a \u00e1rea de seguran\u00e7a, ap\u00f3s a confirma\u00e7\u00e3o de que o governo norte-coreano lan\u00e7ou mais um m\u00edssel b\u00e1listico nas proximidades do Jap\u00e3o. &#8220;Depois do lan\u00e7amento dos m\u00edsseis da Cor\u00e9ia do Norte, \u00e9 mais importante do que nunca financiar nossos militares&#8221;, escreveu Trump.<\/p>\n<p>No mesmo texto, ele disse que os &#8220;dem\u00f4nios&#8221; n\u00e3o devem reter o financiamento de tropas por anistia \u00e0 imigra\u00e7\u00e3o ilegal.\u00a0 Trump se referia \u00e0 bancada democrata que tenta obstruir a vota\u00e7\u00e3o de recursos no Congresso por causa de pol\u00eamicas relacionadas \u00e0 pol\u00edtica imigrat\u00f3ria para imigrantes sem documentos legais.<\/p>\n<p>Antes do coment\u00e1rio do presidente, a porta-voz do Departamento de Estado dos Estados Unidos, Heather Nauert, j\u00e1 havia anunciado que a Casa Branca ir\u00e1 pedir a ado\u00e7\u00e3o de novas san\u00e7\u00f5es contra a Coreia do Norte, perante o Conselho de Seguran\u00e7a da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas &#8211; ONU.<\/p>\n<p>Estados Unidos, Jap\u00e3o e Coreia do Sul pediram ao conselho uma reuni\u00e3o de emerg\u00eancia, mas at\u00e9 a noite de ontem, o local e o hor\u00e1rio ainda n\u00e3o tinham sido divulgados.\u00a0 No entanto, o encontro deve acontecer hoje (29).<\/p>\n<p><strong>M\u00edssil atinge \u00e1guas japonesas<\/strong><\/p>\n<p>O Pent\u00e1gono confirmou que o missil lan\u00e7ado nesta quarta-feira, no hor\u00e1rio da pen\u00ednsula coreana, atingiu \u00e1guas japonesas e chegou a alcan\u00e7ar altitude de 4.500km e voou 960 km.<\/p>\n<p>Antes dele, a Coreia do Norte havia lan\u00e7ado um m\u00edssil em setembro. O pa\u00eds continua realizando testes nucleares e lan\u00e7ando m\u00edsseis, apesar das advert\u00eancias e san\u00e7\u00f5es do Conselho de Seguran\u00e7a da ONU. S\u00f3 no segundo semestre, o pa\u00eds foi sancionado duas vezes pela ONU.<\/p>\n<p>O secret\u00e1rio de Defesa norte-americano, James Mattis, advertiu que o m\u00edssil lan\u00e7ado ontem foi superior aos outros testados anteriormente.<\/p>\n<p>Desde que chegou ao poder, Trump mant\u00e9m um tom provocador e agressivo em rela\u00e7\u00e3o ao l\u00edder norte-coreano, Kim Jong Un, que tamb\u00e9m faz provoca\u00e7\u00f5es. O aumento das tens\u00f5es preocupa os pa\u00edses asi\u00e1ticos na regi\u00e3o.\u00a0 Jap\u00e3o e Coreia do Sul, aliados norte-americanos, n\u00e3o descartam a via militar, mas pedem a tentativa de di\u00e1logo em primeiro plano.<\/p>\n<p>A China, por sua vez, diz que o discurso endurecido e amea\u00e7ador de Washington pode piorar a situa\u00e7\u00e3o. O secret\u00e1rio de Estado norte-americano, Rex Tillerson, chegou a dizer algumas vezes que h\u00e1 um canal secreto de negocia\u00e7\u00f5es entre Washington e Pyongang, mas a ret\u00f3rica de Trump aponta para a dire\u00e7\u00e3o contr\u00e1ria. (ABr)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pelo\u00a0Twitter, o presidente dos Estados Unidos, Donald Trump, defendeu ontem (28) a libera\u00e7\u00e3o de financiamento para a \u00e1rea de seguran\u00e7a, ap\u00f3s a confirma\u00e7\u00e3o de que o governo norte-coreano lan\u00e7ou mais um m\u00edssel b\u00e1listico nas proximidades do Jap\u00e3o. &#8220;Depois do lan\u00e7amento dos m\u00edsseis da Cor\u00e9ia do Norte, \u00e9 mais importante do que nunca financiar nossos militares&#8221;, escreveu Trump. No mesmo texto, ele disse que os &#8220;dem\u00f4nios&#8221; n\u00e3o devem reter o financiamento de tropas por anistia \u00e0 imigra\u00e7\u00e3o ilegal.\u00a0 Trump se referia \u00e0 bancada democrata que tenta obstruir a vota\u00e7\u00e3o de recursos no Congresso por causa de pol\u00eamicas relacionadas \u00e0 pol\u00edtica imigrat\u00f3ria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,8,1],"tags":[],"views":2402,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31799"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=31799"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31799\/revisions"}],"predecessor-version":[{"id":31801,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31799\/revisions\/31801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/31800"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=31799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=31799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=31799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}