{"id":31961,"date":"2017-12-14T17:11:49","date_gmt":"2017-12-14T21:11:49","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=31961"},"modified":"2017-12-14T17:11:49","modified_gmt":"2017-12-14T21:11:49","slug":"onu-ve-porta-entreaberta-para-negociacao-com-a-coreia-do-norte","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2017\/12\/14\/onu-ve-porta-entreaberta-para-negociacao-com-a-coreia-do-norte\/","title":{"rendered":"ONU v\u00ea &#8220;porta entreaberta&#8221; para negocia\u00e7\u00e3o com a Coreia do Norte"},"content":{"rendered":"<p>O subsecret\u00e1rio-geral da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) para Assuntos Pol\u00edticos, Jeffrey Feltman, afirmou nessa ter\u00e7a-feira (12) que, ap\u00f3s sua recente visita a Pyongyang, a capital norte-coreana, acredita que h\u00e1 uma &#8220;porta entreaberta&#8221; para uma sa\u00edda negociada com o pa\u00eds. A informa\u00e7\u00e3o \u00e9 da Ag\u00eancia EFE.<\/p>\n<p>&#8220;O tempo dir\u00e1 sobre o impacto das nossas conversas, mas acredito que deixamos uma porta entreaberta. E espero firmemente que a porta para uma solu\u00e7\u00e3o negociada se abra agora&#8221;, disse Feltman.<\/p>\n<p>O diplomata americano informou ao Conselho de Seguran\u00e7a da ONU os resultados da visita que fez a Pyongyang na \u00faltima semana, o primeiro di\u00e1logo de maior profundidade entre a organiza\u00e7\u00e3o e o governo norte-coreano em quase oito anos.<\/p>\n<p>Feltman disse que Pyongyang n\u00e3o manifestou nenhum compromisso em rela\u00e7\u00e3o \u00e0 sua vontade de negociar com a comunidade internacional, mas se mostrou favor\u00e1vel em continuar o di\u00e1logo com as Na\u00e7\u00f5es Unidas.<\/p>\n<p>Para ele, as autoridades norte-coreanas ainda precisam de algum de tempo para &#8220;digerir&#8221; as conversas e discutir a quest\u00e3o internamente. &#8220;N\u00f3s insistimos na cren\u00e7a de que eles devem indicar se est\u00e3o dispostos a seguir um caminho diferente&#8221;, afirmou.<\/p>\n<p>Feltman insinuou que o governo norte-coreano concentrou grande parte das conversa\u00e7\u00f5es sobre a tens\u00e3o com os Estados Unidos (EUA) e disse ter lembrado \u00e0s autoridades do pa\u00eds que, no que se refere ao seu programa nuclear e de m\u00edsseis, existe um consenso internacional claro.<\/p>\n<p>&#8220;A comunidade internacional est\u00e1 comprometida com uma solu\u00e7\u00e3o pac\u00edfica e pol\u00edtica para a situa\u00e7\u00e3o&#8221; e &#8220;unida na sua oposi\u00e7\u00e3o \u00e0 pesquisa de armas nucleares&#8221; por parte da Coreia do Norte, ressaltou.<\/p>\n<p>O diplomata, do ponto de vista pessoal, reconheceu que a visita ao pa\u00eds asi\u00e1tico foi, sem d\u00favida, a miss\u00e3o mais importante de sua carreira. &#8220;Senti a responsabilidade sobre os meus ombros durante o tempo em que estive ali&#8221;, admitiu.<\/p>\n<p>Tanto a ONU quanto o regime de Kim Jong-un consideraram, durante as conversas, que a situa\u00e7\u00e3o na Pen\u00ednsula coreana \u00e9 atualmente &#8220;a mais tensa e perigosa&#8221; quest\u00e3o de paz e seguran\u00e7a no mundo.<\/p>\n<p>Ao longo dos \u00faltimos meses, Pyongyang fez repetidos testes armament\u00edcios, desafiando as resolu\u00e7\u00f5es das Na\u00e7\u00f5es Unidas e elevando a tens\u00e3o, sobretudo com os EUA.<\/p>\n<p>Hoje, o secret\u00e1rio de Estado americano, Rex Tillerson, afirmou que a Coreia do Norte \u00e9 &#8220;a amea\u00e7a mais imediata&#8221; para o seu pa\u00eds, mas manifestou a inten\u00e7\u00e3o de &#8220;continuar a diplomacia, com a esperan\u00e7a de sucesso at\u00e9 que caia a primeira bomba&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O subsecret\u00e1rio-geral da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) para Assuntos Pol\u00edticos, Jeffrey Feltman, afirmou nessa ter\u00e7a-feira (12) que, ap\u00f3s sua recente visita a Pyongyang, a capital norte-coreana, acredita que h\u00e1 uma &#8220;porta entreaberta&#8221; para uma sa\u00edda negociada com o pa\u00eds. A informa\u00e7\u00e3o \u00e9 da Ag\u00eancia EFE. &#8220;O tempo dir\u00e1 sobre o impacto das nossas conversas, mas acredito que deixamos uma porta entreaberta. E espero firmemente que a porta para uma solu\u00e7\u00e3o negociada se abra agora&#8221;, disse Feltman. O diplomata americano informou ao Conselho de Seguran\u00e7a da ONU os resultados da visita que fez a Pyongyang na \u00faltima semana, o primeiro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31962,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[8,1],"tags":[],"views":2460,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31961"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=31961"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31961\/revisions"}],"predecessor-version":[{"id":31963,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31961\/revisions\/31963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/31962"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=31961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=31961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=31961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}