{"id":31973,"date":"2017-12-14T17:25:28","date_gmt":"2017-12-14T21:25:28","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=31973"},"modified":"2017-12-14T17:25:28","modified_gmt":"2017-12-14T21:25:28","slug":"indocumentado-morre-de-frio-cruzando-a-fronteira-com-texas","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2017\/12\/14\/indocumentado-morre-de-frio-cruzando-a-fronteira-com-texas\/","title":{"rendered":"Indocumentado morre de frio cruzando a fronteira com Texas"},"content":{"rendered":"<p>As temperaturas congelantes do Texas levaram as autoridades de imigra\u00e7\u00e3o a resgatar imigrantes indocumentados na fronteira.<\/p>\n<p>Durante uma das opera\u00e7\u00f5es, agentes descobriram 15 imigrantes guatemaltecos em uma montanha na \u00e1rea de Marfa, a cerca de 400 milhas a oeste de San Antonio. Um comunicado de imprensa do Servi\u00e7o de Prote\u00e7\u00e3o das Alf\u00e2ndegas e Fronteiras explicou que um dos indocumentados foi encontrado morto, enquanto os 14 restantes apresentaram sintomas de hipotermia extrema e exaust\u00e3o.<\/p>\n<p>Agentes de imigra\u00e7\u00e3o encontraram os imigrantes na manh\u00e3 de sexta-feira enquanto patrulhavam a \u00e1rea em um helic\u00f3ptero, onde podiam ver vest\u00edgios na neve. Dos imigrantes sobreviventes, cinco foram removidos da montanha por helic\u00f3ptero em estado cr\u00edtico e nove foram transportados em ve\u00edculos. Eles foram levados de ambul\u00e2ncia para o Big Bend Regional Medical Center para tratamento m\u00e9dico adicional, acrescentou o comunicado.<\/p>\n<p>De acordo com as autoridades, pelo menos um dos pacientes teve uma parada card\u00edaca durante sua transfer\u00eancia, ent\u00e3o ele teve que ser transportado pelo ar para o hospital. A declara\u00e7\u00e3o concluiu que os 15 imigrantes tinham cerca de uma semana passando pelo deserto do Texas antes de serem encontrados, durante este tempo, uma tempestade de inverno atingiu a \u00e1rea, deixando a neve e temperaturas de congelamento na regi\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As temperaturas congelantes do Texas levaram as autoridades de imigra\u00e7\u00e3o a resgatar imigrantes indocumentados na fronteira. Durante uma das opera\u00e7\u00f5es, agentes descobriram 15 imigrantes guatemaltecos em uma montanha na \u00e1rea de Marfa, a cerca de 400 milhas a oeste de San Antonio. Um comunicado de imprensa do Servi\u00e7o de Prote\u00e7\u00e3o das Alf\u00e2ndegas e Fronteiras explicou que um dos indocumentados foi encontrado morto, enquanto os 14 restantes apresentaram sintomas de hipotermia extrema e exaust\u00e3o. Agentes de imigra\u00e7\u00e3o encontraram os imigrantes na manh\u00e3 de sexta-feira enquanto patrulhavam a \u00e1rea em um helic\u00f3ptero, onde podiam ver vest\u00edgios na neve. Dos imigrantes sobreviventes, cinco [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1,10],"tags":[],"views":2976,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31973"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=31973"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31973\/revisions"}],"predecessor-version":[{"id":31975,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/31973\/revisions\/31975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/31974"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=31973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=31973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=31973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}