{"id":32023,"date":"2017-12-21T10:28:47","date_gmt":"2017-12-21T14:28:47","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=32023"},"modified":"2017-12-21T10:28:47","modified_gmt":"2017-12-21T14:28:47","slug":"agenda-cultural-211217-by-roger-costa","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2017\/12\/21\/agenda-cultural-211217-by-roger-costa\/","title":{"rendered":"Agenda Cultural 21\/12\/17, by Roger Costa"},"content":{"rendered":"<p>*Musical Elf oferece magia e encanto \u00e0 toda a fam\u00edlia&gt; Em cartaz at\u00e9 o pr\u00f3ximo dia 29, no teatro do Madison Square Garden em New York, Elf The Musical \u00e9 uma dica saud\u00e1vel para aproveitar com a fam\u00edlia nesta \u00e9poca natalina. A hist\u00f3ria conta as aventuras de Elf, um garoto \u00f3rf\u00e3o que foi levado \u00e0 terra de Santa Claus por engano e agora busca seu pai biol\u00f3gico pelas ruas iluminadas de NY. Ingressos $45-$150. <em>INFO: <\/em><em><a href=\"https:\/\/elfmusicaltour.com\/\">https:\/\/elfmusicaltour.com\/<\/a><\/em><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-32026\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2017\/12\/alvin-ailey.jpg\" alt=\"\" width=\"660\" height=\"371\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2017\/12\/alvin-ailey.jpg 660w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2017\/12\/alvin-ailey-300x169.jpg 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><br \/>\n*\u00daltimos dias para conferir novo espet\u00e1culo da aclamada companhia Alvin Ailey&gt; Uma das maiores e mais respeitadas companhias de dan\u00e7a teatral e moderna americana, Alvin Ailey American Dance Theater, tornou-se refer\u00eancia e influ\u00eancia essenciais no mundo contempor\u00e2neo da dan\u00e7a ao longo das d\u00e9cadas, com trabalhos inspirados pelas ra\u00edzes africanas, tradi\u00e7\u00f5es sociais e culturais e a espiritualidade Gospel. Essencial para essa temporada harmoniosa, a companhia apresenta v\u00e1rios novos trabalhos e tamb\u00e9m cl\u00e1ssicos favoritos como o suntuoso e emocionante &#8220;Revelations&#8221;. Formada por dan\u00e7arinos exuberantes que transcendem com perfei\u00e7\u00e3o a est\u00e9tica vigorosa de suas coreografias, podem ser vistos no NY City Center at\u00e9 31 de dezembro. Ingressos a partir de $29. <em>INFO: <\/em><em><a href=\"https:\/\/www.nycitycenter.org\/pdps\/alvin-ailey\/\">https:\/\/www.nycitycenter.org\/pdps\/alvin-ailey\/<\/a><\/em><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-32027\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2017\/12\/chris-botti.jpg\" alt=\"\" width=\"618\" height=\"348\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2017\/12\/chris-botti.jpg 618w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2017\/12\/chris-botti-300x169.jpg 300w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/><br \/>\n*Instrumentista Chris Botti realiza temporada de shows no Blue Note em Manhattan&gt; O multipremiado trompetista retorna \u00e0 celebrada casa de jazz, localizada no 131 West 3rd Street, pelo 13\u00ba ano para temporada de shows inspirados pelas festas natalinas. Dono de composi\u00e7\u00f5es rom\u00e2nticas, baladas pop e cl\u00e1ssicos mel\u00f3dicos, Botti j\u00e1 colaborou com artistas como Barbra Streisand, Sting, Lady Gaga, e Paul Simon entre outros, e conta com o apoio de talentosos m\u00fasicos e cantoras de arrepiar ao seu lado no palco. At\u00e9 7 de janeiro. Ingressos a partir de $65. <em>INFO: <\/em><em><a href=\"http:\/\/www.bluenote.net\/newyork\/index.shtml\">http:\/\/www.bluenote.net\/newyork\/index.shtml<\/a><\/em><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-32025\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2017\/12\/njpac-rock-interativo.jpg\" alt=\"\" width=\"660\" height=\"340\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2017\/12\/njpac-rock-interativo.jpg 660w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2017\/12\/njpac-rock-interativo-300x155.jpg 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><br \/>\n*NJPAC abriga concerto de Rock Interativo dedicado a cultura de games&gt; O megaevento V\u00eddeo Games Live celebra a diversidade da cultura de v\u00eddeo games com um concerto de rock interativo, interpretando m\u00fasicas originais dos games mais famosos da atualidade, acompanhado de efeitos sincronizados de v\u00eddeo e ilumina\u00e7\u00e3o, criando atmosfera tecno-futurista. Criado e apresentado pelo magnata da ind\u00fastria Tommy Tallarico o evento acontece sexta, dia 29, \u00e0s 7h30 da noite no NJPAC em Newark. Ingressos $39-$69. <em>INFO: <\/em><em><a href=\"http:\/\/www.njpac.org\/events\/detail\/video-games-live-2017\">http:\/\/www.njpac.org\/events\/detail\/video-games-live-2017<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Musical Elf oferece magia e encanto \u00e0 toda a fam\u00edlia&gt; Em cartaz at\u00e9 o pr\u00f3ximo dia 29, no teatro do Madison Square Garden em New York, Elf The Musical \u00e9 uma dica saud\u00e1vel para aproveitar com a fam\u00edlia nesta \u00e9poca natalina. A hist\u00f3ria conta as aventuras de Elf, um garoto \u00f3rf\u00e3o que foi levado \u00e0 terra de Santa Claus por engano e agora busca seu pai biol\u00f3gico pelas ruas iluminadas de NY. Ingressos $45-$150. INFO: https:\/\/elfmusicaltour.com\/ *\u00daltimos dias para conferir novo espet\u00e1culo da aclamada companhia Alvin Ailey&gt; Uma das maiores e mais respeitadas companhias de dan\u00e7a teatral e moderna americana, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[20,1],"tags":[],"views":2622,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/32023"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=32023"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/32023\/revisions"}],"predecessor-version":[{"id":32028,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/32023\/revisions\/32028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/32024"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=32023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=32023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=32023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}