{"id":32036,"date":"2017-12-21T13:05:40","date_gmt":"2017-12-21T17:05:40","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=32036"},"modified":"2017-12-21T13:05:40","modified_gmt":"2017-12-21T17:05:40","slug":"com-a-crise-numero-de-brasileiros-que-deixa-o-pais-dispara","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2017\/12\/21\/com-a-crise-numero-de-brasileiros-que-deixa-o-pais-dispara\/","title":{"rendered":"Com a crise, n\u00famero de brasileiros que deixa o pa\u00eds dispara"},"content":{"rendered":"<p>A quantidade de pessoas que deixou oficialmente o Brasil para morar no exterior subiu 165% nos \u00faltimos sete anos. Em 2011, 8,1 mil declara\u00e7\u00f5es de sa\u00edda definitiva foram entregues \u00e0 Receita Federal. J\u00e1 em 2017, o n\u00famero quase dobrou: 21,7 mil brasileiros deixaram o pa\u00eds at\u00e9 13 de dezembro deste ano (dados mais recentes).<\/p>\n<p>Como explica o &#8216;G1&#8217;, que teve acessos aos dados, o maior salto ocorreu justamente no auge da crise econ\u00f4mica no pa\u00eds, que aconteceu de 2015 a 2016. Neste per\u00edodo, as declara\u00e7\u00f5es saltaram mais de 40%. No ano anterior, o aumento tinha sido de 19% e, de 2013 para 2014, foi 24%. Os dados contabilizam tanto brasileiros quantos estrangeiros que residiam no Brasil.<\/p>\n<p>&#8220;Havia a expectativa de que a economia ia come\u00e7ar a melhorar e tamb\u00e9m um movimento xen\u00f3fobo [no mundo], que poderia desacelerar esse processo [de sa\u00edda do Brasil]. Mas as perspectivas para a pol\u00edtica no ano que vem desanimam&#8221;, explica Jorge Botrel, s\u00f3cio da JBJ Partners, empresa especializada em empreendedorismo e expatria\u00e7\u00e3o para os Estados Unidos.<\/p>\n<p>Segundo o especialista, a demanda por assessoria para deixar o Brasil vem crescendo e o perfil mudou. &#8220;Estamos falando de pessoas qualificadas. O perfil do imigrante n\u00e3o \u00e9 mais aquele que vem com uma m\u00e3o na frente e outra atr\u00e1s. S\u00e3o altos executivos, que est\u00e3o abandonando suas carreiras para abrir um neg\u00f3cio, pessoas com PhD. \u00c9 um movimento triste, porque o Brasil est\u00e1 perdendo recursos&#8221;, lamenta.<\/p>\n<p>De acordo com Botrel, o perfil de emigrantes \u00e9, na maioria, pessoas de 30 a 55 anos, que se mudam com a fam\u00edlia. &#8220;S\u00e3o casais com filhos pequenos que querem dar um futuro melhor para eles, muitos empres\u00e1rios&#8221;, conclui.<\/p>\n<p>Os investimentos de brasileiros em im\u00f3veis no exterior quase dobraram de 2011 para 2016: de US$ 3,6 bilh\u00f5es para US$ 6,1 bilh\u00f5es, segundo o Banco Central.<\/p>\n<p>Os Estados Unidos s\u00e3o o pa\u00eds preferido, que recebeu US$ 2,3 bilh\u00f5es dos aportes em im\u00f3veis no ano passado. Portugal est\u00e1 em segundo lugar, com US$ 725 milh\u00f5es, seguido de Fran\u00e7a (US$ 589 milh\u00f5es) e It\u00e1lia\u00a0(US$ 290 milh\u00f5es).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A quantidade de pessoas que deixou oficialmente o Brasil para morar no exterior subiu 165% nos \u00faltimos sete anos. Em 2011, 8,1 mil declara\u00e7\u00f5es de sa\u00edda definitiva foram entregues \u00e0 Receita Federal. J\u00e1 em 2017, o n\u00famero quase dobrou: 21,7 mil brasileiros deixaram o pa\u00eds at\u00e9 13 de dezembro deste ano (dados mais recentes). Como explica o &#8216;G1&#8217;, que teve acessos aos dados, o maior salto ocorreu justamente no auge da crise econ\u00f4mica no pa\u00eds, que aconteceu de 2015 a 2016. Neste per\u00edodo, as declara\u00e7\u00f5es saltaram mais de 40%. No ano anterior, o aumento tinha sido de 19% e, de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[7,3,1],"tags":[],"views":2431,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/32036"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=32036"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/32036\/revisions"}],"predecessor-version":[{"id":32038,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/32036\/revisions\/32038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/32037"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=32036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=32036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=32036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}