{"id":35441,"date":"2018-08-09T14:04:44","date_gmt":"2018-08-09T18:04:44","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=35441"},"modified":"2018-08-09T14:04:44","modified_gmt":"2018-08-09T18:04:44","slug":"suspeito-pelo-desaparecimento-de-12-brasileiros-em-travessia-para-os-eua-e-preso","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2018\/08\/09\/suspeito-pelo-desaparecimento-de-12-brasileiros-em-travessia-para-os-eua-e-preso\/","title":{"rendered":"Suspeito pelo desaparecimento de 12 brasileiros em travessia para os EUA \u00e9 preso"},"content":{"rendered":"<p>A Pol\u00edcia Federal capturou no \u00faltimo s\u00e1bado, 4, no Panam\u00e1, o principal suspeito pelo desaparecimento de 12 brasileiros, cinco dominicanos e dois cubanos em novembro de 2016, durante uma travessia ilegal de barco das Bahamas para os Estados Unidos.<\/p>\n<p>As informa\u00e7\u00f5es foram divulgadas pela PF na segunda-feira, 6. A a\u00e7\u00e3o \u00e9 resultado da 3.\u00aa fase da\u00a0Opera\u00e7\u00e3o Piratas do Caribe\u00a0e foi realizada em conjunto com a Interpol, ICE e Pol\u00edcias do Panam\u00e1 e Rep\u00fablica Dominicana. O homem, de 40 anos, foi encaminhado para Bras\u00edlia\/DF no domingo (5\/8), onde ficar\u00e1 sob cust\u00f3dia.<\/p>\n<p>Estima-se que a organiza\u00e7\u00e3o criminosa da qual o preso faz parte tenha movimentado, nos \u00faltimos anos, mais de R$ 25 milh\u00f5es e enviado uma m\u00e9dia de 150 adultos e 30 crian\u00e7as e\/ou adolescentes por ano para tentar o ingresso ilegal nos EUA. No curso da investiga\u00e7\u00e3o, foi constatado que diversos brasileiros acabaram morrendo ou desaparecendo enquanto tentavam a travessia.<\/p>\n<p>As investiga\u00e7\u00f5es come\u00e7aram a partir da not\u00edcia do desaparecimento de um brasileiro que teria tentado entrar ilegalmente nos Estados Unidos, em dezembro de 2016, com aux\u00edlio de coiotes. A apura\u00e7\u00e3o indicou que, antes de sair do Brasil, os imigrantes ficavam em cidades com aeroportos internacionais de f\u00e1cil acesso, aguardando a ordem de embarque para as Bahamas onde aguardavam por v\u00e1rios dias para tentar fazer a travessia de barco e, assim, ingressarem clandestinamente nos Estados Unidos.<\/p>\n<p>Al\u00e9m de todos os riscos que envolviam a imigra\u00e7\u00e3o ilegal, os coiotes escondiam os reais perigos envolvidos na travessia, como a passagem pela regi\u00e3o do Tri\u00e2ngulo da Bermudas, famosa pelo alto \u00edndice de tempestades, naufr\u00e1gios e desaparecimento de embarca\u00e7\u00f5es e aeronaves. A opera\u00e7\u00e3o \u00e9 uma das primeiras a serem realizadas no ambiente de Inqu\u00e9rito Policial eletr\u00f4nico (Sistema ePol).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Federal capturou no \u00faltimo s\u00e1bado, 4, no Panam\u00e1, o principal suspeito pelo desaparecimento de 12 brasileiros, cinco dominicanos e dois cubanos em novembro de 2016, durante uma travessia ilegal de barco das Bahamas para os Estados Unidos. As informa\u00e7\u00f5es foram divulgadas pela PF na segunda-feira, 6. A a\u00e7\u00e3o \u00e9 resultado da 3.\u00aa fase da\u00a0Opera\u00e7\u00e3o Piratas do Caribe\u00a0e foi realizada em conjunto com a Interpol, ICE e Pol\u00edcias do Panam\u00e1 e Rep\u00fablica Dominicana. O homem, de 40 anos, foi encaminhado para Bras\u00edlia\/DF no domingo (5\/8), onde ficar\u00e1 sob cust\u00f3dia. Estima-se que a organiza\u00e7\u00e3o criminosa da qual o preso faz [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1,10],"tags":[],"views":1745,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/35441"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=35441"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/35441\/revisions"}],"predecessor-version":[{"id":35443,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/35441\/revisions\/35443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/35442"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=35441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=35441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=35441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}