{"id":35533,"date":"2018-08-16T11:02:32","date_gmt":"2018-08-16T15:02:32","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=35533"},"modified":"2018-08-16T11:02:32","modified_gmt":"2018-08-16T15:02:32","slug":"trump-e-taxa-de-us20-mil-nao-inibem-imigrantes-brasileiros","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2018\/08\/16\/trump-e-taxa-de-us20-mil-nao-inibem-imigrantes-brasileiros\/","title":{"rendered":"Trump e taxa de US$20 mil n\u00e3o inibem imigrantes brasileiros"},"content":{"rendered":"<p>A pol\u00edtica migrat\u00f3ria de toler\u00e2ncia zero do presidente Donald Trump, que vigorou em maio e junho e separou crian\u00e7as dos pais, n\u00e3o inibiu brasileiros de atravessarem ilegalmente a fronteira americana.<\/p>\n<p>A procura continua a mesma, inclusive por parte de fam\u00edlias com filhos pequenos, afirma um coiote que h\u00e1 mais de 20 anos leva imigrantes da regi\u00e3o de Governador Valadares (MG) para os EUA. O coiote diz cobrar US$ 20 mil d\u00f3lares de cada emigrante, isso para os que &#8220;n\u00e3o d\u00e3o trabalho&#8221;. &#8220;Se ele for mais lento, tiver dificuldade de entender as orienta\u00e7\u00f5es, j\u00e1 sei que vai me dar dor de cabe\u00e7a, a\u00ed cobro US$ 22 mil.&#8221; Segundo ele, o dinheiro fica com algum familiar no Brasil e o acerto s\u00f3 \u00e9 feito na chegada ao outro lado da fronteira. Marcelo, nome fict\u00edcio, afirma que com o fim da toler\u00e2ncia zero, as fam\u00edlias com crian\u00e7as que ele envia para os EUA recorrem a um m\u00e9todo conhecido: se entregam \u00e0 patrulha da fronteira e pedem asilo. Nesse caso, o valor pago ao coiote cai pela metade. &#8220;Pais com crian\u00e7as t\u00eam mais chance de entrar. \u00c9 uma viagem mais f\u00e1cil&#8221;, alega.<\/p>\n<p>Ele admite que h\u00e1 casos de crian\u00e7as desacompanhadas que se passam por filhas de outro adulto. &#8220;Se eu estou com um menor desacompanhado e meu colega [outro coiote] tem um adulto sem filhos, ele paga US$ 2.000 para o menor ir como filho dele.&#8221; Segundo Marcelo, a primeira etapa \u00e9 ir de avi\u00e3o at\u00e9 a Cidade do M\u00e9xico. L\u00e1, agentes de imigra\u00e7\u00e3o cobram US$ 1.000,00 por passageiro para permitir o ingresso. &#8220;Temos um contato no aeroporto em todos os turnos. Mandamos as fotos de cada passageiro nosso, dizemos como v\u00e3o vestidos. Se n\u00e3o fizermos isso, eles voltam&#8221;, relata. Os brasileiros v\u00e3o at\u00e9 uma cidade mexicana na fronteira, de \u00f4nibus ou em voos dom\u00e9sticos. Nesse \u00faltimo caso, \u00e9 preciso pagar propina a um policial no aeroporto, US$ 100 por pessoa.<\/p>\n<p>Como \u00e9 feita a travessia depende &#8220;do preparo f\u00edsico do passageiro&#8221;. Os mais resistentes pagam US$ 5.000 para caminhar 10 km pela mata. Pelo mesmo valor, \u00e9 poss\u00edvel percorrer, em boias, um rio que leva aos EUA. Tamb\u00e9m h\u00e1 a op\u00e7\u00e3o de pular o muro na pr\u00f3pria fronteira. &#8220;A gente tem uma pessoa que avisa quando \u00e9 troca de turno dos guardas. A\u00ed eles usam uma escada de corda, que vai de um lado a outro, atravessam e v\u00e3o embora. D\u00e1 tempo, mas tem que ser uma pessoa que aguenta correr.&#8221; Obesos, deficientes, gr\u00e1vidas e idosos t\u00eam a alternativa superluxo, como classifica Marcelo: um caminho de dez minutos dentro de um t\u00fanel que desemboca em uma fazenda nos EUA. O pre\u00e7o cobrado pelos mexicanos somente por esse trajeto \u00e9 o dobro. At\u00e9 um ve\u00edculo dos correios \u00e9 usado: &#8220;A pessoa vai embaixo dos malotes, quietinha. Atravessou o ped\u00e1gio, est\u00e1 livre&#8221;.<\/p>\n<p>Segundo ele, cerca de 10% dos brasileiros que o contratam s\u00e3o pegos pela pol\u00edcia. Nesse caso, ele diz que tem uma rede de advogados para tentar soltar a pessoa sob fian\u00e7a enquanto corre o processo. &#8220;[Nos anos] at\u00e9 que termine o julgamento, mesmo que ela seja deportada, ela j\u00e1 juntou o dinheiro que precisava.&#8221; Marcelo diz que j\u00e1 entrou 35 vezes nos EUA sem ser pego e morou 12 anos l\u00e1. Nas vezes em que foi preso, pensou em desistir de ser coiote, mas voltou \u00e0 atividade ilegal. &#8220;Com o d\u00f3lar chegando a R$ 4, a tenta\u00e7\u00e3o \u00e9 muita. J\u00e1 trabalhei numa empreiteira pegando pesado e ganhando um sal\u00e1rio-m\u00ednimo. N\u00e3o aguentei nem quatro meses&#8221;, diz ele, que compra principalmente im\u00f3veis com o dinheiro ganho. &#8220;N\u00e3o gosto de aparecer. Tenho minha fazendinha, minha piscininha, mas n\u00e3o tenho carro chamativo&#8221;, diz. Para ele, \u00e9 a mesma tenta\u00e7\u00e3o que leva tantos cidad\u00e3os da regi\u00e3o de Governador Valadares a migrarem ilegalmente. Filho de um ferrovi\u00e1rio, Marcelo foi para a Am\u00e9rica do Norte pela primeira vez com 17 anos. Em pouco tempo, conseguiu comprar bens, o que incentivou os vizinhos na cidade de origem a irem. &#8220;Recebi v\u00e1rias &#8216;cantadas&#8217; para levar outras pessoas. Comecei desse jeito.&#8221; Ele afirma que leis e pr\u00e1ticas mais duras como as de Trump n\u00e3o frear\u00e3o os migrantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pol\u00edtica migrat\u00f3ria de toler\u00e2ncia zero do presidente Donald Trump, que vigorou em maio e junho e separou crian\u00e7as dos pais, n\u00e3o inibiu brasileiros de atravessarem ilegalmente a fronteira americana. A procura continua a mesma, inclusive por parte de fam\u00edlias com filhos pequenos, afirma um coiote que h\u00e1 mais de 20 anos leva imigrantes da regi\u00e3o de Governador Valadares (MG) para os EUA. O coiote diz cobrar US$ 20 mil d\u00f3lares de cada emigrante, isso para os que &#8220;n\u00e3o d\u00e3o trabalho&#8221;. &#8220;Se ele for mais lento, tiver dificuldade de entender as orienta\u00e7\u00f5es, j\u00e1 sei que vai me dar dor de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35534,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1,10],"tags":[],"views":2368,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/35533"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=35533"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/35533\/revisions"}],"predecessor-version":[{"id":35535,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/35533\/revisions\/35535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/35534"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=35533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=35533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=35533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}