{"id":4498,"date":"2013-12-12T11:57:41","date_gmt":"2013-12-12T15:57:41","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=4498"},"modified":"2013-12-12T11:57:41","modified_gmt":"2013-12-12T15:57:41","slug":"cruzeiro-admite-interesse-mas-ve-dificuldade-para-tirar-fred-do-flu","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2013\/12\/12\/cruzeiro-admite-interesse-mas-ve-dificuldade-para-tirar-fred-do-flu\/","title":{"rendered":"Cruzeiro admite interesse, mas v\u00ea dificuldade para tirar Fred do Flu"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-4508\" alt=\"fred\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2013\/12\/fred.jpg\" width=\"499\" height=\"333\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2013\/12\/fred.jpg 499w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2013\/12\/fred-300x200.jpg 300w\" sizes=\"(max-width: 499px) 100vw, 499px\" \/><\/p>\n<p>Com passagem marcante pelo Cruzeiro, o atacante Fred \u00e9 um sonho antigo da torcida celeste e principalmente do presidente Gilvan de Pinho Tavares. O clube celeste n\u00e3o esconde o interesse no centroavante da sele\u00e7\u00e3o brasileira, mas admite dificuldade para tir\u00e1-lo do Fluminense.<\/p>\n<p>Com a queda do Fluminense para a S\u00e9rie B do Brasileiro, o diretor de futebol Alexandre Mattos disse que o Cruzeiro avaliar\u00e1 a possibilidade de contratar Fred, por\u00e9m vai esperar para ver a postura clube carioca em rela\u00e7\u00e3o ao atacante.<!--more--><\/p>\n<p>&#8220;O que tem que entender \u00e9 o caminho que o Fred e o Fluminense v\u00e3o adotar. A gente sabe que o Fred tem mais dois anos e meio (<em>de contrato<\/em>) e a not\u00edcia que a gente tem \u00e9 que talvez renovaria at\u00e9 o contrato. A gente n\u00e3o conhece os n\u00fameros do Fred, vamos conhecer at\u00e9 para ver a possibilidade real ou n\u00e3o de uma poss\u00edvel contrata\u00e7\u00e3o&#8221;, afirmou o dirigente, em entrevista a <em>R\u00e1dio Itatiaia<\/em>.<\/p>\n<p>&#8220;Se for poss\u00edvel, analisando o lado t\u00e9cnico, o elenco, a caracter\u00edstica do nosso elenco, e analisando a situa\u00e7\u00e3o financeira do Fred for compat\u00edvel com isso tudo, podemos avan\u00e7ar alguma coisa&#8221;, acrescentou o diretor de futebol.<\/p>\n<p>O gerente de futebol, Valdir Barbosa, mostrou-se mais pessimista em rela\u00e7\u00e3o a um acerto com Fred. Segundo ele, o Fluminense e a Unimed, parceira do clube, dificultar\u00e3o a sa\u00edda do atacante. Para o dirigente, o Cruzeiro tem de aguardar como ficar\u00e1 o tricolor carioca depois da queda para a segunda divis\u00e3o.<\/p>\n<p>&#8220;A gente tem que esperar a poeira baixar, essa queda do Fluminense, ver o reflexo que trar\u00e1 nos pr\u00f3ximos dias para ver se realmente h\u00e1 a possibilidade de negocia\u00e7\u00e3o&#8221;, ressaltou Valdir Barbosa.<\/p>\n<p>Revelado pelo Am\u00e9rica-MG, Fred teve uma passagem curta pelo Cruzeiro, mas suficiente para conquistar a torcida celeste. O atacante chegou \u00e0 Toca da Raposa em meados de 2004 e foi artilheiro do Campeonato Mineiro com 14 gols e da Copa do Brasil, com 15, ambos em 2005. Por\u00e9m, no mesmo ano, foi negociado para o Lyon, da Fran\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com passagem marcante pelo Cruzeiro, o atacante Fred \u00e9 um sonho antigo da torcida celeste e principalmente do presidente Gilvan de Pinho Tavares. O clube celeste n\u00e3o esconde o interesse no centroavante da sele\u00e7\u00e3o brasileira, mas admite dificuldade para tir\u00e1-lo do Fluminense. Com a queda do Fluminense para a S\u00e9rie B do Brasileiro, o diretor de futebol Alexandre Mattos disse que o Cruzeiro avaliar\u00e1 a possibilidade de contratar Fred, por\u00e9m vai esperar para ver a postura clube carioca em rela\u00e7\u00e3o ao atacante.<\/p>\n","protected":false},"author":1,"featured_media":4508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[9,1],"tags":[],"views":2934,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/4498"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=4498"}],"version-history":[{"count":2,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/4498\/revisions"}],"predecessor-version":[{"id":4511,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/4498\/revisions\/4511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/4508"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=4498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=4498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=4498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}