{"id":4506,"date":"2013-12-12T12:07:36","date_gmt":"2013-12-12T16:07:36","guid":{"rendered":"http:\/\/www.brazilianpress.com\/v1\/?p=4506"},"modified":"2013-12-12T12:07:36","modified_gmt":"2013-12-12T16:07:36","slug":"homem-nu-e-preso-durante-protesto-na-suecia-por-chines-e-nobel-da-paz-e-esta-preso","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2013\/12\/12\/homem-nu-e-preso-durante-protesto-na-suecia-por-chines-e-nobel-da-paz-e-esta-preso\/","title":{"rendered":"Homem nu \u00e9 preso durante protesto na Su\u00e9cia por chin\u00eas \u00e9 Nobel da Paz e est\u00e1 preso"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-4519\" alt=\"homem nu suecia\" src=\"http:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2013\/12\/homem-nu-suecia.jpg\" width=\"500\" height=\"363\" srcset=\"https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2013\/12\/homem-nu-suecia.jpg 500w, https:\/\/www.brazilianpress.com\/v1\/wp-content\/uploads\/2013\/12\/homem-nu-suecia-300x217.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Um homem nu foi preso pela pol\u00edcia do lado de fora do Concert Hall em Estocolmo na Su\u00e9cia, na ter\u00e7a-feira (10), durante um protesto de chineses pela pris\u00e3o de Liu Xiaobo, escritor e ativista pelos direitos humanos que lutou por reformas na China e foi agraciado com o Pr\u00eamio Nobel da Paz em 2010. Xiaobo est\u00e1 preso na China h\u00e1 cinco anos e manifestantes realizaram um protesto em Estocolmo pedindo a sua liberta\u00e7\u00e3o.<!--more--><\/p>\n<p>O protesto ocorreu devido \u00e0 entrega do pr\u00eamio Nobel da Paz na ter\u00e7a-feira \u00e0 Organiza\u00e7\u00e3o para a Proibi\u00e7\u00e3o de Armas Qu\u00edmicas (Opaq) devido aos esfor\u00e7os para eliminar as armas de destrui\u00e7\u00e3o em massa no planeta.e a atua\u00e7\u00e3o na guerra civil na S\u00edria. O pr\u00eamio foi entregue em Oslo, na Noruega, pelo rei da Su\u00ed\u00e7a Carlos XVI Gustavo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem nu foi preso pela pol\u00edcia do lado de fora do Concert Hall em Estocolmo na Su\u00e9cia, na ter\u00e7a-feira (10), durante um protesto de chineses pela pris\u00e3o de Liu Xiaobo, escritor e ativista pelos direitos humanos que lutou por reformas na China e foi agraciado com o Pr\u00eamio Nobel da Paz em 2010. Xiaobo est\u00e1 preso na China h\u00e1 cinco anos e manifestantes realizaram um protesto em Estocolmo pedindo a sua liberta\u00e7\u00e3o.<\/p>\n","protected":false},"author":1,"featured_media":4519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[8,1],"tags":[],"views":5644,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/4506"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=4506"}],"version-history":[{"count":2,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/4506\/revisions"}],"predecessor-version":[{"id":4521,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/4506\/revisions\/4521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/4519"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=4506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=4506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=4506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}