{"id":50583,"date":"2021-12-29T10:42:45","date_gmt":"2021-12-29T14:42:45","guid":{"rendered":"https:\/\/www.brazilianpress.com\/v1\/?p=50583"},"modified":"2021-12-29T10:42:45","modified_gmt":"2021-12-29T14:42:45","slug":"homem-encontra-ossada-de-lutador-de-mma-desaparecido-desde-2020-no-missouri","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2021\/12\/29\/homem-encontra-ossada-de-lutador-de-mma-desaparecido-desde-2020-no-missouri\/","title":{"rendered":"Homem encontra ossada de lutador de MMA, desaparecido desde 2020 no Missouri"},"content":{"rendered":"<p><strong>Um homem que procurava chifres de veado em uma floresta no Missouri, nos Estados Unidos, encontrou restos humanos que foram identificados como sendo de um lutador amador de MMA. De acordo com as autoridades locais, a ossada era do atleta David Koenig, desaparecido h\u00e1 cerca de 21 meses.<\/strong><\/p>\n<p>A descoberta p\u00f5e fim \u00e0s buscas por Koenig, que tinha 25 anos quando foi visto pela \u00faltima vez em um motel na cidade de Branson, em fevereiro de 2020. Os restos mortais foram encontrados na floresta nas proximidades da Fall Creek Road, em 22 de dezembro, informou a pol\u00edcia nesta segunda-feira.<\/p>\n<p><img src=\"https:\/\/i.insider.com\/61cb20c607cb8e001811c736?width=700\" alt=\"Human Remains of Amateur MMA Fighter David Koenig Found in Missouri\" \/><\/p>\n<p>Ap\u00f3s encontrar a ossada, o homem comunicou os policiais. Investigadores do Departamento de Pol\u00edcia de Branson fizeram uma &#8220;busca meticulosa&#8221; na \u00e1rea &#8220;\u201crecuperando a maior parte dos restos mortais e v\u00e1rios outros artefatos pessoais\u201d da v\u00edtima. Posteriormente, exames atestaram que os restos mortais eram de Koenig. Um patologista forense determinou \u201cn\u00e3o houve trauma e que a morte n\u00e3o parece ter sido resultado de crime\u201d, segundo nota da pol\u00edcia.<\/p>\n<p><img src=\"https:\/\/www.the-sun.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MF-Skeletal-remains-confirmed-MMA-Fighter-David-Koenig-OFFPLAT.jpg?strip=all&amp;quality=100&amp;w=1200&amp;h=800&amp;crop=1\" alt=\"David Koenig missing update: Skeletal remains found in Missouri confirmed  to be former mixed martial arts fighter\" \/><\/p>\n<p>Desde o desaparecimento, os investigadores passaram milhares de horas procurando por Koenig. \u2014 Nosso departamento e o incr\u00edvel grupo de volunt\u00e1rios nunca pararam em nossos esfor\u00e7os para encontrar o Sr. Koenig \u2014 disse o chefe de pol\u00edcia de Branson, Jeff Matthews. \u2014 Embora este n\u00e3o seja o final que esper\u00e1vamos, oferecemos nossas sinceras condol\u00eancias \u00e0 fam\u00edlia e aos amigos do Sr. Koenig \u2014 acrescentou.<\/p>\n<p><img src=\"https:\/\/bloximages.chicago2.vip.townnews.com\/bransontrilakesnews.com\/content\/tncms\/assets\/v3\/editorial\/e\/b2\/eb2399ae-dc16-11e6-b759-a30a53ce01c0\/587d0c94dc931.image.jpg?resize=500%2C614\" alt=\"Koenig wins in less than a minute again with kimura hold | Sports Free |  bransontrilakesnews.com\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem que procurava chifres de veado em uma floresta no Missouri, nos Estados Unidos, encontrou restos humanos que foram identificados como sendo de um lutador amador de MMA. De acordo com as autoridades locais, a ossada era do atleta David Koenig, desaparecido h\u00e1 cerca de 21 meses. A descoberta p\u00f5e fim \u00e0s buscas por Koenig, que tinha 25 anos quando foi visto pela \u00faltima vez em um motel na cidade de Branson, em fevereiro de 2020. Os restos mortais foram encontrados na floresta nas proximidades da Fall Creek Road, em 22 de dezembro, informou a pol\u00edcia nesta segunda-feira. Ap\u00f3s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50584,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1,10],"tags":[],"views":1512,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/50583"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=50583"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/50583\/revisions"}],"predecessor-version":[{"id":50585,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/50583\/revisions\/50585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/50584"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=50583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=50583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=50583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}