{"id":50596,"date":"2021-12-31T10:33:48","date_gmt":"2021-12-31T14:33:48","guid":{"rendered":"https:\/\/www.brazilianpress.com\/v1\/?p=50596"},"modified":"2021-12-31T10:33:48","modified_gmt":"2021-12-31T14:33:48","slug":"em-manhattan-1-a-cada-50-residentes-testou-positivo-para-covid-19-na-semana-do-natal","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2021\/12\/31\/em-manhattan-1-a-cada-50-residentes-testou-positivo-para-covid-19-na-semana-do-natal\/","title":{"rendered":"Em Manhattan 1 a cada 50 residentes testou positivo para Covid-19, na semana do Natal"},"content":{"rendered":"<p><strong>Aproximadamente 1 em cada 50 residentes de Manhattan testou positivo para COVID-19 na semana passada, de acordo com uma an\u00e1lise de dados\u00a0da NBC de New York, exemplificando a capacidade da variante \u00d4micron de se espalhar rapidamente.\u00a0<\/strong><\/p>\n<p>O equivalente a 2.012 em cada 100.000 residentes no bairro contra\u00edram o v\u00edrus nos \u00faltimos sete dias, informou o ve\u00edculo.\u00a0 Novos casos aumentaram na cidade desde que o primeiro caso da mais nova variante do COVID-19, o \u00d4micron, foi detectado na Big Apple em 2 de dezembro.<\/p>\n<p><img src=\"https:\/\/ogimg.infoglobo.com.br\/in\/25334891-fc3-9dc\/FT1086A\/96803380_WASHINGTON-DCDECEMBER-28-People-wait-in-line-at-a-testing-site-to-receive-a-free-COVID-1.jpg\" alt=\"EUA batem recorde da pandemia, com mais de 260 mil casos de Covid por dia -  Jornal O Globo\" \/><\/p>\n<p>A governadora de New York, Kathy Hochul (D), revelou em uma entrevista coletiva\u00a0no in\u00edcio deste m\u00eas que o primeiro caso da variante \u00d4micron encontrado na cidade estava relacionado a um homem vacinado de Minnesota que viajou para a cidade de New York para uma confer\u00eancia no Javits Center.<\/p>\n<p>Nos \u00faltimos 28 dias, a taxa geral de positividade do COVID-19 nos cinco distritos saltou para 22,49 por cento com as autoridades de sa\u00fade da cidade relatando uma m\u00e9dia de sete dias de mais de 21.000 casos confirmados ou prov\u00e1veis do v\u00edrus, de acordo com dados do departamento sa\u00fade da cidade.\u00a0 As hospitaliza\u00e7\u00f5es continuam baixas na cidade de New York, com\u00a0autoridades de sa\u00fade relatando 332\u00a0novas\u00a0admiss\u00f5es em 26 de dezembro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aproximadamente 1 em cada 50 residentes de Manhattan testou positivo para COVID-19 na semana passada, de acordo com uma an\u00e1lise de dados\u00a0da NBC de New York, exemplificando a capacidade da variante \u00d4micron de se espalhar rapidamente.\u00a0 O equivalente a 2.012 em cada 100.000 residentes no bairro contra\u00edram o v\u00edrus nos \u00faltimos sete dias, informou o ve\u00edculo.\u00a0 Novos casos aumentaram na cidade desde que o primeiro caso da mais nova variante do COVID-19, o \u00d4micron, foi detectado na Big Apple em 2 de dezembro. A governadora de New York, Kathy Hochul (D), revelou em uma entrevista coletiva\u00a0no in\u00edcio deste m\u00eas que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50597,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1,10],"tags":[],"views":946,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/50596"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=50596"}],"version-history":[{"count":2,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/50596\/revisions"}],"predecessor-version":[{"id":50599,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/50596\/revisions\/50599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/50597"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=50596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=50596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=50596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}