{"id":52711,"date":"2022-08-20T10:17:50","date_gmt":"2022-08-20T14:17:50","guid":{"rendered":"https:\/\/www.brazilianpress.com\/v1\/?p=52711"},"modified":"2022-08-20T10:17:50","modified_gmt":"2022-08-20T14:17:50","slug":"aviao-com-brasileiros-deportados-que-pousou-em-mg-tinha-todos-os-passageiros-algemados","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2022\/08\/20\/aviao-com-brasileiros-deportados-que-pousou-em-mg-tinha-todos-os-passageiros-algemados\/","title":{"rendered":"Avi\u00e3o com brasileiros deportados, que pousou em MG, tinha todos os passageiros algemados"},"content":{"rendered":"<p><strong>Na \u00faltima semana, um voo com dezenas de brasileiros deportados dos Estados Unidos aterrissou no aeroporto internacional de Confins, na regi\u00e3o metropolitana de Belo Horizonte. Diferentemente da maioria dos voos com essas caracter\u00edsticas, que s\u00e3o operados com aeronaves menores,\u00a0esse voo em quest\u00e3o foi operado com um Boeing 767-300ER de 375 lugares.<\/strong><\/p>\n<p>Apesar do n\u00famero exato de ocupantes n\u00e3o ter sido divulgado, fontes no aeroporto mineiro informaram que o n\u00famero teria sido superior a cem pessoas, todas elas retidas na fronteira dos EUA com o M\u00e9xico. O retorno, por sua vez, acontece atrav\u00e9s de Minas Gerais, por ser um ponto de origem hist\u00f3rico da maioria desses candidatos a imigrantes.<\/p>\n<p>Uma outra triste realidade sobre o voo \u00e9 que\u00a0as pessoas a bordo viajavam algemadas ao assento, por motivos de seguran\u00e7a. Isso independe do perfil e do fato de que a maioria s\u00e3o pessoas de bem, que tentaram a sorte de passar pela fronteira americana para tentar uma vida melhor nos Estados Unidos.<\/p>\n<p>Ao chegar ao Brasil, elas s\u00e3o entregues \u00e0 Pol\u00edcia Federal para triagem e provid\u00eancias, j\u00e1 que h\u00e1 hist\u00f3rico de situa\u00e7\u00f5es em que pessoas procuradas pela justi\u00e7a brasileira estavam a bordo e foram presas ap\u00f3s o desembarque.<\/p>\n<p>Para fins de registro, como apontam os dados da ferramenta ADS-B Exchange, o voo foi operado pelo Boeing 767-300ER de matr\u00edcula N342AX, pertencente \u00e0 Omni Air International, companhia especializada em voos fretados que mant\u00e9m contratos com o governo dos EUA.<\/p>\n<p>Desde que o ex-presidente dos Estados Unidos, Donald Trump, instituiu os voos de deporta\u00e7\u00e3o dos estrangeiros que tentavam ingresso ilegal em territ\u00f3rio americano, as opera\u00e7\u00f5es jamais deixaram de acontecer. Mesmo depois que Joe Biden assumiu a Casa Branca, a pr\u00e1tica seguiu firme, embora muitos esperassem que fosse diminuir de intensidade ou mesmo cessar.<\/p>\n<p>Esses voos, que s\u00e3o operados \u00e0s custas do pr\u00f3prio governo americano, t\u00eam por destinos os mais variados pontos da Am\u00e9rica Latina, devolvendo aos seus pa\u00edses homens, mulheres e crian\u00e7as que tentaram entrar ilegalmente nos EUA e acabaram retidos na fronteira. Nessa contagem de expulsos, um grande n\u00famero de brasileiros est\u00e1 inclu\u00eddo. Ao longo dos anos, j\u00e1 foram dezenas de voos partindo de \u00e1reas de fronteira nos EUA para o Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima semana, um voo com dezenas de brasileiros deportados dos Estados Unidos aterrissou no aeroporto internacional de Confins, na regi\u00e3o metropolitana de Belo Horizonte. Diferentemente da maioria dos voos com essas caracter\u00edsticas, que s\u00e3o operados com aeronaves menores,\u00a0esse voo em quest\u00e3o foi operado com um Boeing 767-300ER de 375 lugares. Apesar do n\u00famero exato de ocupantes n\u00e3o ter sido divulgado, fontes no aeroporto mineiro informaram que o n\u00famero teria sido superior a cem pessoas, todas elas retidas na fronteira dos EUA com o M\u00e9xico. O retorno, por sua vez, acontece atrav\u00e9s de Minas Gerais, por ser um ponto de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42882,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[7,1],"tags":[],"views":3492,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/52711"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=52711"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/52711\/revisions"}],"predecessor-version":[{"id":52712,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/52711\/revisions\/52712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/42882"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=52711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=52711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=52711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}