{"id":52728,"date":"2022-08-23T14:04:26","date_gmt":"2022-08-23T18:04:26","guid":{"rendered":"https:\/\/www.brazilianpress.com\/v1\/?p=52728"},"modified":"2022-08-23T14:04:26","modified_gmt":"2022-08-23T18:04:26","slug":"advogado-e-preso-no-texas-por-suspeita-de-contrabando-de-pessoas-e-resistencia-a-prisao","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2022\/08\/23\/advogado-e-preso-no-texas-por-suspeita-de-contrabando-de-pessoas-e-resistencia-a-prisao\/","title":{"rendered":"Advogado \u00e9 preso no Texas por suspeita de contrabando de pessoas e resist\u00eancia \u00e0 pris\u00e3o"},"content":{"rendered":"<p><strong>Um advogado de Corpus Christi que alegou trabalhar para o governo federal em casos de imigra\u00e7\u00e3o foi preso no condado de Kinney por suspeita de contrabando de seres humanos e resist\u00eancia \u00e0 pris\u00e3o, de acordo com um policial que trabalha perto da fronteira sul na Opera\u00e7\u00e3o Lone Star.<\/strong><br \/>\n<strong>O policial dois do condado de Galveston, Jimmy Fullen, est\u00e1 entre os muitos policiais de todo o estado que est\u00e3o auxiliando a patrulha de fronteira e as autoridades locais na resposta \u00e0 imigra\u00e7\u00e3o ilegal.<\/strong><\/p>\n<p>\u201cUm advogado licenciado do Texas e magistrado de imigra\u00e7\u00e3o nomeado pelo governo federal foi recentemente preso no condado de Kinney, Texas, por contrabando de um humano e resist\u00eancia \u00e0 pris\u00e3o\u201d, escreveu Fullen no Facebook . \u201c\u00d3timo trabalho, Delegado Gonzalez e Troopers que estavam na cena ajudando.\u201d O policial postou imagens dos sujeitos presos, incluindo o advogado Timothy Daniel Japhet. Fullen incluiu uma fotografia da licen\u00e7a legal de Japhet, que indicava que ele foi licenciado em maio de 2003.<\/p>\n<p>Fullen disse ao The Texan na segunda-feira que um de seus deputados prendeu Japhet, que alegou na \u00e9poca ser um magistrado federal de imigra\u00e7\u00e3o. O policial o levou sob cust\u00f3dia com um oficial do Departamento de Seguran\u00e7a P\u00fablica do Texas, explicou Fullen, e acusou Japhet de resistir \u00e0 pris\u00e3o. Japhet teria sido detido em 13 de agosto e mantido por seis dias antes de ser libertado sob fian\u00e7a de US$ 40.000. Ele foi acusado de quatro acusa\u00e7\u00f5es de contrabando de seres humanos.<\/p>\n<p>O advogado disse a uma afiliada da ABC em Corpus Christi que achava que estava apenas pegando caronas em seu caminho para visitar o Lucky Eagle Casino em Eagle Pass. Ele tamb\u00e9m negou ser acusado de resistir \u00e0 pris\u00e3o. Ele disse ao 3NEWS que ficou desconfort\u00e1vel com os quatro indiv\u00edduos que havia pego, ent\u00e3o come\u00e7ou a acelerar, na esperan\u00e7a de atrair a aten\u00e7\u00e3o da pol\u00edcia e ser parado. Japhet tamb\u00e9m afirmou que n\u00e3o \u00e9 um magistrado federal de imigra\u00e7\u00e3o, mas lida com casos envolvendo propriedades no M\u00e9xico, informou a ag\u00eancia. A Opera\u00e7\u00e3o Lone Star \u00e9 uma estrat\u00e9gia de aplica\u00e7\u00e3o da lei lan\u00e7ada pelo governador Greg Abbott para combater a imigra\u00e7\u00e3o ilegal. Quase 300.000 estrangeiros ilegais foram presos pela pol\u00edcia estadual, Guarda Nacional e outros que trabalham na opera\u00e7\u00e3o desde o in\u00edcio em mar\u00e7o de 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um advogado de Corpus Christi que alegou trabalhar para o governo federal em casos de imigra\u00e7\u00e3o foi preso no condado de Kinney por suspeita de contrabando de seres humanos e resist\u00eancia \u00e0 pris\u00e3o, de acordo com um policial que trabalha perto da fronteira sul na Opera\u00e7\u00e3o Lone Star. O policial dois do condado de Galveston, Jimmy Fullen, est\u00e1 entre os muitos policiais de todo o estado que est\u00e3o auxiliando a patrulha de fronteira e as autoridades locais na resposta \u00e0 imigra\u00e7\u00e3o ilegal. \u201cUm advogado licenciado do Texas e magistrado de imigra\u00e7\u00e3o nomeado pelo governo federal foi recentemente preso no condado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52729,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1,10],"tags":[],"views":1017,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/52728"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=52728"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/52728\/revisions"}],"predecessor-version":[{"id":52730,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/52728\/revisions\/52730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/52729"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=52728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=52728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=52728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}