{"id":55260,"date":"2023-07-13T11:29:43","date_gmt":"2023-07-13T15:29:43","guid":{"rendered":"https:\/\/www.brazilianpress.com\/v1\/?p=55260"},"modified":"2023-07-13T11:29:43","modified_gmt":"2023-07-13T15:29:43","slug":"video-brasileiro-de-14-anos-morre-atropelado-em-south-river-nj-e-momento-e-gravado-em-video","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2023\/07\/13\/video-brasileiro-de-14-anos-morre-atropelado-em-south-river-nj-e-momento-e-gravado-em-video\/","title":{"rendered":"V\u00cdDEO: Brasileiro de 14 anos morre atropelado em South River, NJ e momento \u00e9 gravado em v\u00eddeo"},"content":{"rendered":"<p><strong>Brasileiro de 14 anos morre atropelado em NJ e momento \u00e9 gravado em v\u00eddeo <\/strong><strong>Imagens de c\u00e2meras de seguran\u00e7a mostram o momento em que Bryan Barbosa, de 14 anos, \u00e9 atropelado e morto por uma van\u00a0em New Jersey. O caso aconteceu na tarde da sexta-feira (7).\u00a0<\/strong><\/p>\n<p>As imagens flagraram o instante em que Bryan atravessa a rua de bicicleta e \u00e9 atingido pelo motorista, que passa por cima do adolescente em vez de parar o ve\u00edculo. Segundo a pol\u00edcia local, o suspeito fugiu sem prestar socorro. De acordo com o Departamento de Pol\u00edcia de South River, ele foi encaminhado para um hospital, mas n\u00e3o resistiu aos ferimentos e faleceu. O suspeito, Michael Arena, de 63 anos, foi preso em casa.<\/p>\n<div class=\"mnmd-responsive-video\"><iframe loading=\"lazy\" title=\"Jovem brasileiro de 14 anos morre atropelado nos EUA | Primeiro Impacto (13\/07\/23)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/A4JrVv48aA4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<p>O homem admitiu que estava dirigindo o ve\u00edculo no momento do acidente e foi acusado de homic\u00eddio culposo, com o agravante de ter abandonado o local do crime. O suspeito est\u00e1 detido no Centro Correcional de Adultos do Condado de Middlesex e vai aguardar a audi\u00eancia do Tribunal Superior. Desde a sexta-feira, vizinhos, amigos e familiares de Bryan t\u00eam feito homenagens, memoriais e vigias no local onde ele foi morto.\u00a0 A v\u00edtima nasceu em Minas Gerais e foi morar nos EUA quando o pai se mudou para a cidade; a fam\u00edlia toda foi junto logo em seguida. O corpo de Bryan foi liberado para que a fam\u00edlia fa\u00e7a o vel\u00f3rio e deve chegar a Divin\u00f3polis.<\/p>\n<p><img src=\"https:\/\/conteudo.imguol.com.br\/c\/noticias\/58\/2023\/07\/12\/bryan-luiz-de-carvalho-barbosa-que-nasceu-em-divinopolis-morreu-na-ultima-sexta-feira-7-1689193231816_v2_900x506.png\" alt=\"V\u00eddeo mostra morte de brasileiro de 14 anos atropelado por van nos EUA\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brasileiro de 14 anos morre atropelado em NJ e momento \u00e9 gravado em v\u00eddeo Imagens de c\u00e2meras de seguran\u00e7a mostram o momento em que Bryan Barbosa, de 14 anos, \u00e9 atropelado e morto por uma van\u00a0em New Jersey. O caso aconteceu na tarde da sexta-feira (7).\u00a0 As imagens flagraram o instante em que Bryan atravessa a rua de bicicleta e \u00e9 atingido pelo motorista, que passa por cima do adolescente em vez de parar o ve\u00edculo. Segundo a pol\u00edcia local, o suspeito fugiu sem prestar socorro. De acordo com o Departamento de Pol\u00edcia de South River, ele foi encaminhado para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55261,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[4,3,1],"tags":[],"views":2550,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/55260"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=55260"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/55260\/revisions"}],"predecessor-version":[{"id":55262,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/55260\/revisions\/55262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/55261"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=55260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=55260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=55260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}