{"id":55275,"date":"2023-07-17T12:53:06","date_gmt":"2023-07-17T16:53:06","guid":{"rendered":"https:\/\/www.brazilianpress.com\/v1\/?p=55275"},"modified":"2023-07-17T12:53:06","modified_gmt":"2023-07-17T16:53:06","slug":"video-fantastico-questiona-tratamento-para-alzheimer-e-parkinson-oferecido-por-medico-brasileiro-nos-eua","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2023\/07\/17\/video-fantastico-questiona-tratamento-para-alzheimer-e-parkinson-oferecido-por-medico-brasileiro-nos-eua\/","title":{"rendered":"V\u00cdDEO: &#8220;Fant\u00e1stico&#8221; questiona tratamento para Alzheimer e Parkinson oferecido por m\u00e9dico brasileiro nos EUA"},"content":{"rendered":"<p><strong>Um m\u00e9dico brasileiro radicado nos Estados Unidos \u00e9 suspeito de oferecer um tratamento sem comprova\u00e7\u00e3o cient\u00edfica que supostamente curaria doen\u00e7as graves, como c\u00e2ncer, Alzheimer e Parkinson. O curr\u00edculo do profissional tamb\u00e9m traz inconsist\u00eancias. O caso foi revelado pelo Fant\u00e1stico.<\/strong><\/p>\n<div class=\"mnmd-responsive-video\"><iframe loading=\"lazy\" title=\"Fant\u00e1stico(16.07.23)-M\u00e9dico brasileiro oferece tratamento sem comprova\u00e7\u00e3o cient\u00edfica por R$ 200 mil\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/Gv6BCECOc_k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<p>M\u00e1rcio Aur\u00e9lio Martins Abreu, conhecido nos EUA como Marc Abreu, se formou no Brasil em oftalmologia e est\u00e1 nos Estados Unidos h\u00e1 mais de duas d\u00e9cadas. Em 2003, ele anunciou a descoberta do t\u00fanel t\u00e9rmico cerebral, uma esp\u00e9cie de pele que permitiria medir a temperatura do c\u00e9rebro de forma n\u00e3o-invasiva. O term\u00f4metro criado pelo m\u00e9dico foi aprovado pela FDA, a ag\u00eancia de sa\u00fade dos EUA.<\/p>\n<p><img src=\"https:\/\/pbs.twimg.com\/ext_tw_video_thumb\/1680751759378055170\/pu\/img\/-TwfsuSaHGwzk23T?format=jpg&amp;name=large\" alt=\"Fant\u00e1stico (@showdavida) \/ Twitter\" \/><\/p>\n<p>Em abril de 2023, o brasileiro anunciou que um paciente dele havia tido remiss\u00e3o completa de um c\u00e2ncer de pr\u00f3stata em est\u00e1gio 4. O tratamento utilizado teria como base o term\u00f4metro cerebral. O m\u00e9dico coloca o paciente em um tubo de alta temperatura e supostamente enviaria sinais para o c\u00e9rebro, por meio do term\u00f4metro criado por ele. Esse processo ativar c\u00e9lulas de choque t\u00e9rmico que, supostamente, curaria doen\u00e7as graves.<\/p>\n<p>\/\/ Fonte: Itatiaia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um m\u00e9dico brasileiro radicado nos Estados Unidos \u00e9 suspeito de oferecer um tratamento sem comprova\u00e7\u00e3o cient\u00edfica que supostamente curaria doen\u00e7as graves, como c\u00e2ncer, Alzheimer e Parkinson. O curr\u00edculo do profissional tamb\u00e9m traz inconsist\u00eancias. O caso foi revelado pelo Fant\u00e1stico. M\u00e1rcio Aur\u00e9lio Martins Abreu, conhecido nos EUA como Marc Abreu, se formou no Brasil em oftalmologia e est\u00e1 nos Estados Unidos h\u00e1 mais de duas d\u00e9cadas. Em 2003, ele anunciou a descoberta do t\u00fanel t\u00e9rmico cerebral, uma esp\u00e9cie de pele que permitiria medir a temperatura do c\u00e9rebro de forma n\u00e3o-invasiva. O term\u00f4metro criado pelo m\u00e9dico foi aprovado pela FDA, a ag\u00eancia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55276,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[4,3,1],"tags":[],"views":975,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/55275"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=55275"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/55275\/revisions"}],"predecessor-version":[{"id":55277,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/55275\/revisions\/55277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/55276"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=55275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=55275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=55275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}