{"id":58957,"date":"2024-10-10T14:50:56","date_gmt":"2024-10-10T18:50:56","guid":{"rendered":"https:\/\/www.brazilianpress.com\/v1\/?p=58957"},"modified":"2024-10-10T14:50:56","modified_gmt":"2024-10-10T18:50:56","slug":"comunidade-processo-de-liberdade-condicional-humanitaria-nao-sera-prorrogado-pelos-estados-unidos","status":"publish","type":"post","link":"https:\/\/www.brazilianpress.com\/v1\/2024\/10\/10\/comunidade-processo-de-liberdade-condicional-humanitaria-nao-sera-prorrogado-pelos-estados-unidos\/","title":{"rendered":"Comunidade: Processo de liberdade condicional humanit\u00e1ria n\u00e3o ser\u00e1 prorrogado pelos Estados Unidos"},"content":{"rendered":"<p><strong>O governo dos Estados Unidos anunciou que n\u00e3o prorrogar\u00e1 o estatuto legal tempor\u00e1rio de dezenas de milhares de migrantes que entraram no pa\u00eds ao abrigo de um programa conhecido como\u00a0<em>liberdade condicional<\/em>\u00a0implementado durante a administra\u00e7\u00e3o de Joe Biden.<\/strong><\/p>\n<p>Este programa, concebido para reduzir as entradas ilegais atrav\u00e9s da fronteira sul, permitiu que migrantes venezuelanos, haitianos, cubanos e nicaraguenses entrassem legalmente nos Estados Unidos na esperan\u00e7a de se estabilizarem e procurarem oportunidades de asilo ou obterem benef\u00edcios de imigra\u00e7\u00e3o.<\/p>\n<p>Um comunicado do Departamento de Seguran\u00e7a Interna (DHS) foi claro desde o in\u00edcio quanto ao car\u00e1ter tempor\u00e1rio deste programa.<\/p>\n<p>Conforme estipulado no\u00a0<em>Cadastro Federal<\/em>, a autoriza\u00e7\u00e3o concedida neste processo\u00a0tinha a dura\u00e7\u00e3o de at\u00e9 dois anos. Durante este per\u00edodo, os migrantes tiveram que aproveitar a oportunidade para procurar ajuda humanit\u00e1ria ou benef\u00edcios de imigra\u00e7\u00e3o que lhes permitissem regularizar o seu estatuto de longo prazo. Esta autoriza\u00e7\u00e3o tamb\u00e9m lhes permitiu trabalhar legalmente nos Estados Unidos e contribuir para a economia nacional.<\/p>\n<p>Os n\u00fameros oficiais indicam que os encontros fronteiri\u00e7os de migrantes destes pa\u00edses diminu\u00edram em mais de 99% em compara\u00e7\u00e3o com os n\u00edveis anteriores \u00e0 implementa\u00e7\u00e3o do programa. Ao oferecer um caminho legal, as autoridades esperavam dissuadir outras pessoas de arriscarem as suas vidas ao atravessarem ilegalmente, muitas vezes sob o controle de perigosas redes de contrabando de seres humanos.<\/p>\n<p>Apesar da natureza tempor\u00e1ria do programa, as autoridades destacaram que os benefici\u00e1rios do programa que ainda n\u00e3o regularizaram a sua situa\u00e7\u00e3o podem procurar op\u00e7\u00f5es de ajuda humanit\u00e1ria ou de imigra\u00e7\u00e3o atrav\u00e9s dos Servi\u00e7os de Cidadania e Imigra\u00e7\u00e3o dos Estados Unidos. Entre as alternativas mais comuns est\u00e3o os pedidos de asilo ou o Estatuto de Prote\u00e7\u00e3o Tempor\u00e1ria (TPS), embora estas op\u00e7\u00f5es n\u00e3o sejam garantidas e dependam das circunst\u00e2ncias individuais de cada migrante.<\/p>\n<p>O USCIS continua a aceitar novas inscri\u00e7\u00f5es para o processo de patroc\u00ednio atrav\u00e9s do Formul\u00e1rio I-134A e implementou medidas adicionais para fortalecer a avalia\u00e7\u00e3o dos patrocinadores para garantir que atendam aos requisitos exigidos. Este processo rigoroso visa garantir que os benefici\u00e1rios do programa possam entrar nos Estados Unidos de forma segura e ordenada.<\/p>\n<p>A decis\u00e3o de n\u00e3o prorrogar o estatuto tempor\u00e1rio dos migrantes levantou cr\u00edticas por parte dos defensores dos direitos dos migrantes, que argumentam que muitos destes indiv\u00edduos ainda n\u00e3o conseguiram regularizar a sua situa\u00e7\u00e3o devido a atrasos no processamento dos pedidos ou \u00e0 complexidade dos procedimentos de imigra\u00e7\u00e3o.<\/p>\n<p>Segundo fontes oficiais, aqueles que n\u00e3o conseguirem regularizar a sua situa\u00e7\u00e3o antes de expirar a autoriza\u00e7\u00e3o de resid\u00eancia enfrentar\u00e3o a deporta\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo dos Estados Unidos anunciou que n\u00e3o prorrogar\u00e1 o estatuto legal tempor\u00e1rio de dezenas de milhares de migrantes que entraram no pa\u00eds ao abrigo de um programa conhecido como\u00a0liberdade condicional\u00a0implementado durante a administra\u00e7\u00e3o de Joe Biden. Este programa, concebido para reduzir as entradas ilegais atrav\u00e9s da fronteira sul, permitiu que migrantes venezuelanos, haitianos, cubanos e nicaraguenses entrassem legalmente nos Estados Unidos na esperan\u00e7a de se estabilizarem e procurarem oportunidades de asilo ou obterem benef\u00edcios de imigra\u00e7\u00e3o. Um comunicado do Departamento de Seguran\u00e7a Interna (DHS) foi claro desde o in\u00edcio quanto ao car\u00e1ter tempor\u00e1rio deste programa. Conforme estipulado no\u00a0Cadastro Federal, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58958,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[4,1],"tags":[],"views":588,"_links":{"self":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/58957"}],"collection":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/comments?post=58957"}],"version-history":[{"count":1,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/58957\/revisions"}],"predecessor-version":[{"id":58959,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/posts\/58957\/revisions\/58959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media\/58958"}],"wp:attachment":[{"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/media?parent=58957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/categories?post=58957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brazilianpress.com\/v1\/wp-json\/wp\/v2\/tags?post=58957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}